{"id":13041,"date":"2025-01-08T14:06:59","date_gmt":"2025-01-08T14:06:59","guid":{"rendered":"https:\/\/www.yverdon-energies.ch\/?post_type=programes&#038;p=13041"},"modified":"2026-01-13T18:10:02","modified_gmt":"2026-01-13T16:10:02","slug":"infrastructure-de-recharge-a-usage-prive-intelligent","status":"publish","type":"programes","link":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/","title":{"rendered":"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent"},"content":{"rendered":"\n<section class=\"inner_page_banner h_auto mb-0 pb-0 \" id=\"\">\n    <div class=\"sey_inner_page_container \">\n                <div class=\"row\">\n            <div class=\"col-xl-8 col-lg-12 h-100\">\n                <div class=\"inner_page_banner_txt mw-100  banner_wave_text\">\n                                            <h1>Borne de recharge intelligente<\/h1>\n                                                                <p>Installez des bornes de recharges de mani\u00e8re coordonn\u00e9e dans les immeubles collectifs et profitez de la subvention \u00e9quiwatt.<\/p>\n                                                        <\/div>\n                                \n            <\/div>\n            \n                            <div class=\"col-xl-4 col-lg-12\">\n                    <div class=\"banner_right_wave\">\n                        <img decoding=\"async\" src=\"#\" alt=\"\" class=\"banner_wave\">\n                    <\/div>\n                <\/div>\n            \n                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n    <section class=\"simple_img_block \" id=\"\">\n        <div class=\"sey_inner_page_container\">\n            <div class=\"row\">\n                <div class=\"col-sm-12\">\n                    <img decoding=\"async\" src=\"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/YLBE_2026_Banners_Site_web_SEY_V04.jpg\" class=\"w-100\" alt=\"\">\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n   \n\n<section class=\"text_with_wave no_bg\" id=\"\">\n    <div class=\"sey_inner_page_container\">\n                <svg style=\"bottom: 0;\" width=\"488\" height=\"151\" viewBox=\"0 0 488 151\" fill=\"none\"\n            xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"wv_lp\">\n            <g clip-path=\"url(#clip0_1140_15955)\">\n                <path\n                    d=\"M248.62 15.551C239.79 21.671 232.16 26.961 216.04 26.961C199.92 26.961 192.29 21.671 183.46 15.551C174.3 9.20098 163.92 2.00098 144.04 2.00098H144.02C124.14 2.00098 113.76 9.20098 104.6 15.551C95.7701 21.671 88.15 26.961 72.04 26.961C55.9301 26.961 48.2999 21.671 39.48 15.551C30.3199 9.20098 19.9401 2.00098 0.0600586 2.00098H0.0400391C-19.84 2.00098 -30.22 9.20098 -39.38 15.551C-48.21 21.671 -55.84 26.961 -71.96 26.961C-88.08 26.961 -95.71 21.671 -104.54 15.551C-113.7 9.20098 -124.08 2.00098 -143.96 2.00098H-143.98C-163.85 2.00098 -174.23 9.20098 -183.39 15.551C-192.22 21.671 -199.85 26.961 -215.96 26.961C-232.07 26.961 -239.7 21.671 -248.53 15.551C-257.69 9.20098 -268.07 2.00098 -287.95 2.00098H-287.96C-307.83 2.00098 -318.22 9.20098 -327.38 15.551C-336.21 21.671 -343.84 26.961 -359.96 26.961C-376.08 26.961 -383.71 21.671 -392.54 15.551C-401.7 9.20098 -412.08 2.00098 -431.96 2.00098H-431.98C-451.86 2.00098 -462.24 9.20098 -471.4 15.551C-480.23 21.671 -487.86 26.961 -503.97 26.961C-520.08 26.961 -527.71 21.671 -536.54 15.551C-545.7 9.20098 -556.08 2.00098 -575.96 2.00098H-575.98C-595.85 2.00098 -606.24 9.20098 -615.4 15.551C-624.23 21.671 -631.86 26.961 -647.98 26.961C-664.1 26.961 -671.73 21.671 -680.56 15.551C-689.72 9.20098 -700.1 2.00098 -719.98 2.00098H-720C-739.88 2.00098 -750.26 9.20098 -759.42 15.551C-768.25 21.671 -775.88 26.961 -791.99 26.961C-808.1 26.961 -815.73 21.671 -824.56 15.551C-833.72 9.20098 -844.1 2.00098 -863.98 2.00098H-864C-883.87 2.00098 -894.26 9.20098 -903.42 15.551C-912.25 21.671 -919.88 26.961 -936 26.961C-952.12 26.961 -959.75 21.671 -968.58 15.551C-977.74 9.20098 -988.13 2.00098 -1008.01 2.00098C-1027.89 2.00098 -1038.27 9.20098 -1047.43 15.551C-1056.26 21.671 -1063.89 26.961 -1080.03 26.961C-1096.17 26.961 -1103.77 21.671 -1112.6 15.551C-1121.76 9.20098 -1132.13 2.00098 -1152 2.00098V14.001C-1135.89 14.001 -1128.27 19.291 -1119.44 25.411C-1110.28 31.761 -1099.9 38.961 -1080.03 38.961C-1060.16 38.961 -1049.76 31.761 -1040.6 25.411C-1031.77 19.291 -1024.14 14.001 -1008.02 14.001C-991.9 14.001 -984.26 19.291 -975.42 25.411C-966.26 31.761 -955.88 38.961 -936 38.961C-916.12 38.961 -905.74 31.761 -896.58 25.411C-887.75 19.291 -880.12 14.001 -863.99 14.001C-847.88 14.001 -840.26 19.291 -831.44 25.411C-822.28 31.761 -811.9 38.961 -792.03 38.961H-791.97C-772.1 38.961 -761.72 31.761 -752.56 25.411C-743.74 19.291 -736.11 14.001 -720.01 14.001C-703.88 14.001 -696.25 19.291 -687.42 25.411C-678.26 31.761 -667.88 38.961 -648 38.961C-628.12 38.961 -617.74 31.761 -608.58 25.411C-599.75 19.291 -592.12 14.001 -575.99 14.001C-559.88 14.001 -552.26 19.291 -543.44 25.411C-534.28 31.761 -523.9 38.961 -504.03 38.961H-503.97C-484.1 38.961 -473.72 31.761 -464.56 25.411C-455.74 19.291 -448.11 14.001 -432.01 14.001C-415.88 14.001 -408.25 19.291 -399.42 25.411C-390.26 31.761 -379.88 38.961 -360 38.961C-340.12 38.961 -329.74 31.761 -320.58 25.411C-311.75 19.291 -304.12 14.001 -287.99 14.001C-271.88 14.001 -264.26 19.291 -255.44 25.411C-246.28 31.761 -235.9 38.961 -216.03 38.961H-215.97C-196.1 38.961 -185.72 31.761 -176.56 25.411C-167.74 19.291 -160.12 14.001 -144.01 14.001C-127.88 14.001 -120.25 19.291 -111.42 25.411C-102.26 31.761 -91.88 38.961 -72 38.961C-52.12 38.961 -41.74 31.761 -32.58 25.411C-23.75 19.291 -16.12 14.001 0.0100098 14.001C16.12 14.001 23.7401 19.291 32.5601 25.411C41.7201 31.761 52.1001 38.961 71.9701 38.961H72.03C91.9 38.961 102.28 31.761 111.44 25.411C120.26 19.291 127.89 14.001 143.99 14.001C160.12 14.001 167.75 19.291 176.58 25.411C185.74 31.761 196.12 38.961 216 38.961C235.88 38.961 246.26 31.761 255.42 25.411C264.26 19.291 271.89 14.001 288.02 14.001V2.00098C268.13 2.00098 257.74 9.20098 248.58 15.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 15.551C1679.81 21.671 1672.18 26.961 1656.06 26.961C1639.94 26.961 1632.31 21.671 1623.48 15.551C1614.32 9.20098 1603.94 2.00098 1584.06 2.00098H1584.04C1564.16 2.00098 1553.78 9.20098 1544.62 15.551C1535.79 21.671 1528.17 26.961 1512.06 26.961C1495.95 26.961 1488.32 21.671 1479.5 15.551C1470.34 9.20098 1459.96 2.00098 1440.08 2.00098H1440.06C1420.18 2.00098 1409.8 9.20098 1400.64 15.551C1391.81 21.671 1384.18 26.961 1368.06 26.961C1351.94 26.961 1344.31 21.671 1335.48 15.551C1326.32 9.20098 1315.94 2.00098 1296.06 2.00098H1296.04C1276.17 2.00098 1265.79 9.20098 1256.63 15.551C1247.8 21.671 1240.17 26.961 1224.06 26.961C1207.95 26.961 1200.32 21.671 1191.49 15.551C1182.33 9.20098 1171.95 2.00098 1152.07 2.00098H1152.06C1132.19 2.00098 1121.8 9.20098 1112.64 15.551C1103.81 21.671 1096.18 26.961 1080.06 26.961C1063.94 26.961 1056.31 21.671 1047.48 15.551C1038.32 9.20098 1027.94 2.00098 1008.06 2.00098H1008.04C988.16 2.00098 977.78 9.20098 968.62 15.551C959.79 21.671 952.16 26.961 936.05 26.961C919.94 26.961 912.31 21.671 903.48 15.551C894.32 9.20098 883.94 2.00098 864.06 2.00098H864.04C844.17 2.00098 833.78 9.20098 824.62 15.551C815.79 21.671 808.16 26.961 792.04 26.961C775.92 26.961 768.29 21.671 759.46 15.551C750.3 9.20098 739.92 2.00098 720.04 2.00098H720.02C700.14 2.00098 689.76 9.20098 680.6 15.551C671.77 21.671 664.14 26.961 648.03 26.961C631.92 26.961 624.29 21.671 615.46 15.551C606.3 9.20098 595.92 2.00098 576.04 2.00098H576.02C556.15 2.00098 545.76 9.20098 536.6 15.551C527.77 21.671 520.14 26.961 504.02 26.961C487.9 26.961 480.27 21.671 471.44 15.551C462.28 9.20098 451.89 2.00098 432.01 2.00098C412.13 2.00098 401.75 9.20098 392.59 15.551C383.76 21.671 376.13 26.961 359.99 26.961C343.85 26.961 336.25 21.671 327.42 15.551C318.26 9.20098 307.89 2.00098 288.02 2.00098V14.001C304.13 14.001 311.75 19.291 320.58 25.411C329.74 31.761 340.12 38.961 359.99 38.961C379.86 38.961 390.26 31.761 399.42 25.411C408.25 19.291 415.88 14.001 432 14.001C448.12 14.001 455.76 19.291 464.6 25.411C473.76 31.761 484.14 38.961 504.02 38.961C523.9 38.961 534.28 31.761 543.44 25.411C552.27 19.291 559.9 14.001 576.03 14.001C592.14 14.001 599.76 19.291 608.58 25.411C617.74 31.761 628.12 38.961 647.99 38.961H648.05C667.92 38.961 678.3 31.761 687.46 25.411C696.28 19.291 703.91 14.001 720.01 14.001C736.14 14.001 743.77 19.291 752.6 25.411C761.76 31.761 772.14 38.961 792.02 38.961C811.9 38.961 822.28 31.761 831.44 25.411C840.27 19.291 847.9 14.001 864.03 14.001C880.14 14.001 887.76 19.291 896.58 25.411C905.74 31.761 916.12 38.961 935.99 38.961H936.05C955.92 38.961 966.3 31.761 975.46 25.411C984.28 19.291 991.91 14.001 1008.01 14.001C1024.14 14.001 1031.77 19.291 1040.6 25.411C1049.76 31.761 1060.14 38.961 1080.02 38.961C1099.9 38.961 1110.28 31.761 1119.44 25.411C1128.27 19.291 1135.9 14.001 1152.03 14.001C1168.14 14.001 1175.76 19.291 1184.58 25.411C1193.74 31.761 1204.12 38.961 1223.99 38.961H1224.05C1243.92 38.961 1254.3 31.761 1263.46 25.411C1272.28 19.291 1279.9 14.001 1296.01 14.001C1312.14 14.001 1319.77 19.291 1328.6 25.411C1337.76 31.761 1348.14 38.961 1368.02 38.961C1387.9 38.961 1398.28 31.761 1407.44 25.411C1416.27 19.291 1423.9 14.001 1440.03 14.001C1456.14 14.001 1463.76 19.291 1472.58 25.411C1481.74 31.761 1492.12 38.961 1511.99 38.961H1512.05C1531.92 38.961 1542.3 31.761 1551.46 25.411C1560.28 19.291 1567.91 14.001 1584.01 14.001C1600.14 14.001 1607.77 19.291 1616.6 25.411C1625.76 31.761 1636.14 38.961 1656.02 38.961C1675.9 38.961 1686.28 31.761 1695.44 25.411C1704.28 19.291 1711.91 14.001 1728.04 14.001V2.00098C1708.15 2.00098 1697.76 9.20098 1688.6 15.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 52.551C239.79 58.671 232.16 63.961 216.04 63.961C199.92 63.961 192.29 58.671 183.46 52.551C174.3 46.201 163.92 39.001 144.04 39.001H144.02C124.14 39.001 113.76 46.201 104.6 52.551C95.7701 58.671 88.15 63.961 72.04 63.961C55.9301 63.961 48.2999 58.671 39.48 52.551C30.3199 46.201 19.9401 39.001 0.0600586 39.001H0.0400391C-19.84 39.001 -30.22 46.201 -39.38 52.551C-48.21 58.671 -55.84 63.961 -71.96 63.961C-88.08 63.961 -95.71 58.671 -104.54 52.551C-113.7 46.201 -124.08 39.001 -143.96 39.001H-143.98C-163.85 39.001 -174.23 46.201 -183.39 52.551C-192.22 58.671 -199.85 63.961 -215.96 63.961C-232.07 63.961 -239.7 58.671 -248.53 52.551C-257.69 46.201 -268.07 39.001 -287.95 39.001H-287.96C-307.83 39.001 -318.22 46.201 -327.38 52.551C-336.21 58.671 -343.84 63.961 -359.96 63.961C-376.08 63.961 -383.71 58.671 -392.54 52.551C-401.7 46.201 -412.08 39.001 -431.96 39.001H-431.98C-451.86 39.001 -462.24 46.201 -471.4 52.551C-480.23 58.671 -487.86 63.961 -503.97 63.961C-520.08 63.961 -527.71 58.671 -536.54 52.551C-545.7 46.201 -556.08 39.001 -575.96 39.001H-575.98C-595.85 39.001 -606.24 46.201 -615.4 52.551C-624.23 58.671 -631.86 63.961 -647.98 63.961C-664.1 63.961 -671.73 58.671 -680.56 52.551C-689.72 46.201 -700.1 39.001 -719.98 39.001H-720C-739.88 39.001 -750.26 46.201 -759.42 52.551C-768.25 58.671 -775.88 63.961 -791.99 63.961C-808.1 63.961 -815.73 58.671 -824.56 52.551C-833.72 46.201 -844.1 39.001 -863.98 39.001H-864C-883.87 39.001 -894.26 46.201 -903.42 52.551C-912.25 58.671 -919.88 63.961 -936 63.961C-952.12 63.961 -959.75 58.671 -968.58 52.551C-977.74 46.201 -988.13 39.001 -1008.01 39.001C-1027.89 39.001 -1038.27 46.201 -1047.43 52.551C-1056.26 58.671 -1063.89 63.961 -1080.03 63.961C-1096.17 63.961 -1103.77 58.671 -1112.6 52.551C-1121.76 46.201 -1132.13 39.001 -1152 39.001V51.001C-1135.89 51.001 -1128.27 56.291 -1119.44 62.411C-1110.28 68.761 -1099.9 75.961 -1080.03 75.961C-1060.16 75.961 -1049.76 68.761 -1040.6 62.411C-1031.77 56.291 -1024.14 51.001 -1008.02 51.001C-991.9 51.001 -984.26 56.291 -975.42 62.411C-966.26 68.761 -955.88 75.961 -936 75.961C-916.12 75.961 -905.74 68.761 -896.58 62.411C-887.75 56.291 -880.12 51.001 -863.99 51.001C-847.88 51.001 -840.26 56.291 -831.44 62.411C-822.28 68.761 -811.9 75.961 -792.03 75.961H-791.97C-772.1 75.961 -761.72 68.761 -752.56 62.411C-743.74 56.291 -736.11 51.001 -720.01 51.001C-703.88 51.001 -696.25 56.291 -687.42 62.411C-678.26 68.761 -667.88 75.961 -648 75.961C-628.12 75.961 -617.74 68.761 -608.58 62.411C-599.75 56.291 -592.12 51.001 -575.99 51.001C-559.88 51.001 -552.26 56.291 -543.44 62.411C-534.28 68.761 -523.9 75.961 -504.03 75.961H-503.97C-484.1 75.961 -473.72 68.761 -464.56 62.411C-455.74 56.291 -448.11 51.001 -432.01 51.001C-415.88 51.001 -408.25 56.291 -399.42 62.411C-390.26 68.761 -379.88 75.961 -360 75.961C-340.12 75.961 -329.74 68.761 -320.58 62.411C-311.75 56.291 -304.12 51.001 -287.99 51.001C-271.88 51.001 -264.26 56.291 -255.44 62.411C-246.28 68.761 -235.9 75.961 -216.03 75.961H-215.97C-196.1 75.961 -185.72 68.761 -176.56 62.411C-167.74 56.291 -160.12 51.001 -144.01 51.001C-127.88 51.001 -120.25 56.291 -111.42 62.411C-102.26 68.761 -91.88 75.961 -72 75.961C-52.12 75.961 -41.74 68.761 -32.58 62.411C-23.75 56.291 -16.12 51.001 0.0100098 51.001C16.12 51.001 23.7401 56.291 32.5601 62.411C41.7201 68.761 52.1001 75.961 71.9701 75.961H72.03C91.9 75.961 102.28 68.761 111.44 62.411C120.26 56.291 127.89 51.001 143.99 51.001C160.12 51.001 167.75 56.291 176.58 62.411C185.74 68.761 196.12 75.961 216 75.961C235.88 75.961 246.26 68.761 255.42 62.411C264.26 56.291 271.89 51.001 288.02 51.001V39.001C268.13 39.001 257.74 46.201 248.58 52.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 52.551C1679.81 58.671 1672.18 63.961 1656.06 63.961C1639.94 63.961 1632.31 58.671 1623.48 52.551C1614.32 46.201 1603.94 39.001 1584.06 39.001H1584.04C1564.16 39.001 1553.78 46.201 1544.62 52.551C1535.79 58.671 1528.17 63.961 1512.06 63.961C1495.95 63.961 1488.32 58.671 1479.5 52.551C1470.34 46.201 1459.96 39.001 1440.08 39.001H1440.06C1420.18 39.001 1409.8 46.201 1400.64 52.551C1391.81 58.671 1384.18 63.961 1368.06 63.961C1351.94 63.961 1344.31 58.671 1335.48 52.551C1326.32 46.201 1315.94 39.001 1296.06 39.001H1296.04C1276.17 39.001 1265.79 46.201 1256.63 52.551C1247.8 58.671 1240.17 63.961 1224.06 63.961C1207.95 63.961 1200.32 58.671 1191.49 52.551C1182.33 46.201 1171.95 39.001 1152.07 39.001H1152.06C1132.19 39.001 1121.8 46.201 1112.64 52.551C1103.81 58.671 1096.18 63.961 1080.06 63.961C1063.94 63.961 1056.31 58.671 1047.48 52.551C1038.32 46.201 1027.94 39.001 1008.06 39.001H1008.04C988.16 39.001 977.78 46.201 968.62 52.551C959.79 58.671 952.16 63.961 936.05 63.961C919.94 63.961 912.31 58.671 903.48 52.551C894.32 46.201 883.94 39.001 864.06 39.001H864.04C844.17 39.001 833.78 46.201 824.62 52.551C815.79 58.671 808.16 63.961 792.04 63.961C775.92 63.961 768.29 58.671 759.46 52.551C750.3 46.201 739.92 39.001 720.04 39.001H720.02C700.14 39.001 689.76 46.201 680.6 52.551C671.77 58.671 664.14 63.961 648.03 63.961C631.92 63.961 624.29 58.671 615.46 52.551C606.3 46.201 595.92 39.001 576.04 39.001H576.02C556.15 39.001 545.76 46.201 536.6 52.551C527.77 58.671 520.14 63.961 504.02 63.961C487.9 63.961 480.27 58.671 471.44 52.551C462.28 46.201 451.89 39.001 432.01 39.001C412.13 39.001 401.75 46.201 392.59 52.551C383.76 58.671 376.13 63.961 359.99 63.961C343.85 63.961 336.25 58.671 327.42 52.551C318.26 46.201 307.89 39.001 288.02 39.001V51.001C304.13 51.001 311.75 56.291 320.58 62.411C329.74 68.761 340.12 75.961 359.99 75.961C379.86 75.961 390.26 68.761 399.42 62.411C408.25 56.291 415.88 51.001 432 51.001C448.12 51.001 455.76 56.291 464.6 62.411C473.76 68.761 484.14 75.961 504.02 75.961C523.9 75.961 534.28 68.761 543.44 62.411C552.27 56.291 559.9 51.001 576.03 51.001C592.14 51.001 599.76 56.291 608.58 62.411C617.74 68.761 628.12 75.961 647.99 75.961H648.05C667.92 75.961 678.3 68.761 687.46 62.411C696.28 56.291 703.91 51.001 720.01 51.001C736.14 51.001 743.77 56.291 752.6 62.411C761.76 68.761 772.14 75.961 792.02 75.961C811.9 75.961 822.28 68.761 831.44 62.411C840.27 56.291 847.9 51.001 864.03 51.001C880.14 51.001 887.76 56.291 896.58 62.411C905.74 68.761 916.12 75.961 935.99 75.961H936.05C955.92 75.961 966.3 68.761 975.46 62.411C984.28 56.291 991.91 51.001 1008.01 51.001C1024.14 51.001 1031.77 56.291 1040.6 62.411C1049.76 68.761 1060.14 75.961 1080.02 75.961C1099.9 75.961 1110.28 68.761 1119.44 62.411C1128.27 56.291 1135.9 51.001 1152.03 51.001C1168.14 51.001 1175.76 56.291 1184.58 62.411C1193.74 68.761 1204.12 75.961 1223.99 75.961H1224.05C1243.92 75.961 1254.3 68.761 1263.46 62.411C1272.28 56.291 1279.9 51.001 1296.01 51.001C1312.14 51.001 1319.77 56.291 1328.6 62.411C1337.76 68.761 1348.14 75.961 1368.02 75.961C1387.9 75.961 1398.28 68.761 1407.44 62.411C1416.27 56.291 1423.9 51.001 1440.03 51.001C1456.14 51.001 1463.76 56.291 1472.58 62.411C1481.74 68.761 1492.12 75.961 1511.99 75.961H1512.05C1531.92 75.961 1542.3 68.761 1551.46 62.411C1560.28 56.291 1567.91 51.001 1584.01 51.001C1600.14 51.001 1607.77 56.291 1616.6 62.411C1625.76 68.761 1636.14 75.961 1656.02 75.961C1675.9 75.961 1686.28 68.761 1695.44 62.411C1704.28 56.291 1711.91 51.001 1728.04 51.001V39.001C1708.15 39.001 1697.76 46.201 1688.6 52.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 89.551C239.79 95.671 232.16 100.961 216.04 100.961C199.92 100.961 192.29 95.671 183.46 89.551C174.3 83.201 163.92 76.001 144.04 76.001H144.02C124.14 76.001 113.76 83.201 104.6 89.551C95.7701 95.671 88.15 100.961 72.04 100.961C55.9301 100.961 48.2999 95.671 39.48 89.551C30.3199 83.201 19.9401 76.001 0.0600586 76.001H0.0400391C-19.84 76.001 -30.22 83.201 -39.38 89.551C-48.21 95.671 -55.84 100.961 -71.96 100.961C-88.08 100.961 -95.71 95.671 -104.54 89.551C-113.7 83.201 -124.08 76.001 -143.96 76.001H-143.98C-163.85 76.001 -174.23 83.201 -183.39 89.551C-192.22 95.671 -199.85 100.961 -215.96 100.961C-232.07 100.961 -239.7 95.671 -248.53 89.551C-257.69 83.201 -268.07 76.001 -287.95 76.001H-287.96C-307.83 76.001 -318.22 83.201 -327.38 89.551C-336.21 95.671 -343.84 100.961 -359.96 100.961C-376.08 100.961 -383.71 95.671 -392.54 89.551C-401.7 83.201 -412.08 76.001 -431.96 76.001H-431.98C-451.86 76.001 -462.24 83.201 -471.4 89.551C-480.23 95.671 -487.86 100.961 -503.97 100.961C-520.08 100.961 -527.71 95.671 -536.54 89.551C-545.7 83.201 -556.08 76.001 -575.96 76.001H-575.98C-595.85 76.001 -606.24 83.201 -615.4 89.551C-624.23 95.671 -631.86 100.961 -647.98 100.961C-664.1 100.961 -671.73 95.671 -680.56 89.551C-689.72 83.201 -700.1 76.001 -719.98 76.001H-720C-739.88 76.001 -750.26 83.201 -759.42 89.551C-768.25 95.671 -775.88 100.961 -791.99 100.961C-808.1 100.961 -815.73 95.671 -824.56 89.551C-833.72 83.201 -844.1 76.001 -863.98 76.001H-864C-883.87 76.001 -894.26 83.201 -903.42 89.551C-912.25 95.671 -919.88 100.961 -936 100.961C-952.12 100.961 -959.75 95.671 -968.58 89.551C-977.74 83.201 -988.13 76.001 -1008.01 76.001C-1027.89 76.001 -1038.27 83.201 -1047.43 89.551C-1056.26 95.671 -1063.89 100.961 -1080.03 100.961C-1096.17 100.961 -1103.77 95.671 -1112.6 89.551C-1121.76 83.201 -1132.13 76.001 -1152 76.001V88.001C-1135.89 88.001 -1128.27 93.291 -1119.44 99.411C-1110.28 105.761 -1099.9 112.961 -1080.03 112.961C-1060.16 112.961 -1049.76 105.761 -1040.6 99.411C-1031.77 93.291 -1024.14 88.001 -1008.02 88.001C-991.9 88.001 -984.26 93.291 -975.42 99.411C-966.26 105.761 -955.88 112.961 -936 112.961C-916.12 112.961 -905.74 105.761 -896.58 99.411C-887.75 93.291 -880.12 88.001 -863.99 88.001C-847.88 88.001 -840.26 93.291 -831.44 99.411C-822.28 105.761 -811.9 112.961 -792.03 112.961H-791.97C-772.1 112.961 -761.72 105.761 -752.56 99.411C-743.74 93.291 -736.11 88.001 -720.01 88.001C-703.88 88.001 -696.25 93.291 -687.42 99.411C-678.26 105.761 -667.88 112.961 -648 112.961C-628.12 112.961 -617.74 105.761 -608.58 99.411C-599.75 93.291 -592.12 88.001 -575.99 88.001C-559.88 88.001 -552.26 93.291 -543.44 99.411C-534.28 105.761 -523.9 112.961 -504.03 112.961H-503.97C-484.1 112.961 -473.72 105.761 -464.56 99.411C-455.74 93.291 -448.11 88.001 -432.01 88.001C-415.88 88.001 -408.25 93.291 -399.42 99.411C-390.26 105.761 -379.88 112.961 -360 112.961C-340.12 112.961 -329.74 105.761 -320.58 99.411C-311.75 93.291 -304.12 88.001 -287.99 88.001C-271.88 88.001 -264.26 93.291 -255.44 99.411C-246.28 105.761 -235.9 112.961 -216.03 112.961H-215.97C-196.1 112.961 -185.72 105.761 -176.56 99.411C-167.74 93.291 -160.12 88.001 -144.01 88.001C-127.88 88.001 -120.25 93.291 -111.42 99.411C-102.26 105.761 -91.88 112.961 -72 112.961C-52.12 112.961 -41.74 105.761 -32.58 99.411C-23.75 93.291 -16.12 88.001 0.0100098 88.001C16.12 88.001 23.7401 93.291 32.5601 99.411C41.7201 105.761 52.1001 112.961 71.9701 112.961H72.03C91.9 112.961 102.28 105.761 111.44 99.411C120.26 93.291 127.89 88.001 143.99 88.001C160.12 88.001 167.75 93.291 176.58 99.411C185.74 105.761 196.12 112.961 216 112.961C235.88 112.961 246.26 105.761 255.42 99.411C264.26 93.291 271.89 88.001 288.02 88.001V76.001C268.13 76.001 257.74 83.201 248.58 89.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 89.551C1679.81 95.671 1672.18 100.961 1656.06 100.961C1639.94 100.961 1632.31 95.671 1623.48 89.551C1614.32 83.201 1603.94 76.001 1584.06 76.001H1584.04C1564.16 76.001 1553.78 83.201 1544.62 89.551C1535.79 95.671 1528.17 100.961 1512.06 100.961C1495.95 100.961 1488.32 95.671 1479.5 89.551C1470.34 83.201 1459.96 76.001 1440.08 76.001H1440.06C1420.18 76.001 1409.8 83.201 1400.64 89.551C1391.81 95.671 1384.18 100.961 1368.06 100.961C1351.94 100.961 1344.31 95.671 1335.48 89.551C1326.32 83.201 1315.94 76.001 1296.06 76.001H1296.04C1276.17 76.001 1265.79 83.201 1256.63 89.551C1247.8 95.671 1240.17 100.961 1224.06 100.961C1207.95 100.961 1200.32 95.671 1191.49 89.551C1182.33 83.201 1171.95 76.001 1152.07 76.001H1152.06C1132.19 76.001 1121.8 83.201 1112.64 89.551C1103.81 95.671 1096.18 100.961 1080.06 100.961C1063.94 100.961 1056.31 95.671 1047.48 89.551C1038.32 83.201 1027.94 76.001 1008.06 76.001H1008.04C988.16 76.001 977.78 83.201 968.62 89.551C959.79 95.671 952.16 100.961 936.05 100.961C919.94 100.961 912.31 95.671 903.48 89.551C894.32 83.201 883.94 76.001 864.06 76.001H864.04C844.17 76.001 833.78 83.201 824.62 89.551C815.79 95.671 808.16 100.961 792.04 100.961C775.92 100.961 768.29 95.671 759.46 89.551C750.3 83.201 739.92 76.001 720.04 76.001H720.02C700.14 76.001 689.76 83.201 680.6 89.551C671.77 95.671 664.14 100.961 648.03 100.961C631.92 100.961 624.29 95.671 615.46 89.551C606.3 83.201 595.92 76.001 576.04 76.001H576.02C556.15 76.001 545.76 83.201 536.6 89.551C527.77 95.671 520.14 100.961 504.02 100.961C487.9 100.961 480.27 95.671 471.44 89.551C462.28 83.201 451.89 76.001 432.01 76.001C412.13 76.001 401.75 83.201 392.59 89.551C383.76 95.671 376.13 100.961 359.99 100.961C343.85 100.961 336.25 95.671 327.42 89.551C318.26 83.201 307.89 76.001 288.02 76.001V88.001C304.13 88.001 311.75 93.291 320.58 99.411C329.74 105.761 340.12 112.961 359.99 112.961C379.86 112.961 390.26 105.761 399.42 99.411C408.25 93.291 415.88 88.001 432 88.001C448.12 88.001 455.76 93.291 464.6 99.411C473.76 105.761 484.14 112.961 504.02 112.961C523.9 112.961 534.28 105.761 543.44 99.411C552.27 93.291 559.9 88.001 576.03 88.001C592.14 88.001 599.76 93.291 608.58 99.411C617.74 105.761 628.12 112.961 647.99 112.961H648.05C667.92 112.961 678.3 105.761 687.46 99.411C696.28 93.291 703.91 88.001 720.01 88.001C736.14 88.001 743.77 93.291 752.6 99.411C761.76 105.761 772.14 112.961 792.02 112.961C811.9 112.961 822.28 105.761 831.44 99.411C840.27 93.291 847.9 88.001 864.03 88.001C880.14 88.001 887.76 93.291 896.58 99.411C905.74 105.761 916.12 112.961 935.99 112.961H936.05C955.92 112.961 966.3 105.761 975.46 99.411C984.28 93.291 991.91 88.001 1008.01 88.001C1024.14 88.001 1031.77 93.291 1040.6 99.411C1049.76 105.761 1060.14 112.961 1080.02 112.961C1099.9 112.961 1110.28 105.761 1119.44 99.411C1128.27 93.291 1135.9 88.001 1152.03 88.001C1168.14 88.001 1175.76 93.291 1184.58 99.411C1193.74 105.761 1204.12 112.961 1223.99 112.961H1224.05C1243.92 112.961 1254.3 105.761 1263.46 99.411C1272.28 93.291 1279.9 88.001 1296.01 88.001C1312.14 88.001 1319.77 93.291 1328.6 99.411C1337.76 105.761 1348.14 112.961 1368.02 112.961C1387.9 112.961 1398.28 105.761 1407.44 99.411C1416.27 93.291 1423.9 88.001 1440.03 88.001C1456.14 88.001 1463.76 93.291 1472.58 99.411C1481.74 105.761 1492.12 112.961 1511.99 112.961H1512.05C1531.92 112.961 1542.3 105.761 1551.46 99.411C1560.28 93.291 1567.91 88.001 1584.01 88.001C1600.14 88.001 1607.77 93.291 1616.6 99.411C1625.76 105.761 1636.14 112.961 1656.02 112.961C1675.9 112.961 1686.28 105.761 1695.44 99.411C1704.28 93.291 1711.91 88.001 1728.04 88.001V76.001C1708.15 76.001 1697.76 83.201 1688.6 89.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 126.551C239.79 132.671 232.16 137.961 216.04 137.961C199.92 137.961 192.29 132.671 183.46 126.551C174.3 120.201 163.92 113.001 144.04 113.001H144.02C124.14 113.001 113.76 120.201 104.6 126.551C95.7701 132.671 88.15 137.961 72.04 137.961C55.9301 137.961 48.2999 132.671 39.48 126.551C30.3199 120.201 19.9401 113.001 0.0600586 113.001H0.0400391C-19.84 113.001 -30.22 120.201 -39.38 126.551C-48.21 132.671 -55.84 137.961 -71.96 137.961C-88.08 137.961 -95.71 132.671 -104.54 126.551C-113.7 120.201 -124.08 113.001 -143.96 113.001H-143.98C-163.85 113.001 -174.23 120.201 -183.39 126.551C-192.22 132.671 -199.85 137.961 -215.96 137.961C-232.07 137.961 -239.7 132.671 -248.53 126.551C-257.69 120.201 -268.07 113.001 -287.95 113.001H-287.96C-307.83 113.001 -318.22 120.201 -327.38 126.551C-336.21 132.671 -343.84 137.961 -359.96 137.961C-376.08 137.961 -383.71 132.671 -392.54 126.551C-401.7 120.201 -412.08 113.001 -431.96 113.001H-431.98C-451.86 113.001 -462.24 120.201 -471.4 126.551C-480.23 132.671 -487.86 137.961 -503.97 137.961C-520.08 137.961 -527.71 132.671 -536.54 126.551C-545.7 120.201 -556.08 113.001 -575.96 113.001H-575.98C-595.85 113.001 -606.24 120.201 -615.4 126.551C-624.23 132.671 -631.86 137.961 -647.98 137.961C-664.1 137.961 -671.73 132.671 -680.56 126.551C-689.72 120.201 -700.1 113.001 -719.98 113.001H-720C-739.88 113.001 -750.26 120.201 -759.42 126.551C-768.25 132.671 -775.88 137.961 -791.99 137.961C-808.1 137.961 -815.73 132.671 -824.56 126.551C-833.72 120.201 -844.1 113.001 -863.98 113.001H-864C-883.87 113.001 -894.26 120.201 -903.42 126.551C-912.25 132.671 -919.88 137.961 -936 137.961C-952.12 137.961 -959.75 132.671 -968.58 126.551C-977.74 120.201 -988.13 113.001 -1008.01 113.001C-1027.89 113.001 -1038.27 120.201 -1047.43 126.551C-1056.26 132.671 -1063.89 137.961 -1080.03 137.961C-1096.17 137.961 -1103.77 132.671 -1112.6 126.551C-1121.76 120.201 -1132.13 113.001 -1152 113.001V125.001C-1135.89 125.001 -1128.27 130.291 -1119.44 136.411C-1110.28 142.761 -1099.9 149.961 -1080.03 149.961C-1060.16 149.961 -1049.76 142.761 -1040.6 136.411C-1031.77 130.291 -1024.14 125.001 -1008.02 125.001C-991.9 125.001 -984.26 130.291 -975.42 136.411C-966.26 142.761 -955.88 149.961 -936 149.961C-916.12 149.961 -905.74 142.761 -896.58 136.411C-887.75 130.291 -880.12 125.001 -863.99 125.001C-847.88 125.001 -840.26 130.291 -831.44 136.411C-822.28 142.761 -811.9 149.961 -792.03 149.961H-791.97C-772.1 149.961 -761.72 142.761 -752.56 136.411C-743.74 130.291 -736.11 125.001 -720.01 125.001C-703.88 125.001 -696.25 130.291 -687.42 136.411C-678.26 142.761 -667.88 149.961 -648 149.961C-628.12 149.961 -617.74 142.761 -608.58 136.411C-599.75 130.291 -592.12 125.001 -575.99 125.001C-559.88 125.001 -552.26 130.291 -543.44 136.411C-534.28 142.761 -523.9 149.961 -504.03 149.961H-503.97C-484.1 149.961 -473.72 142.761 -464.56 136.411C-455.74 130.291 -448.11 125.001 -432.01 125.001C-415.88 125.001 -408.25 130.291 -399.42 136.411C-390.26 142.761 -379.88 149.961 -360 149.961C-340.12 149.961 -329.74 142.761 -320.58 136.411C-311.75 130.291 -304.12 125.001 -287.99 125.001C-271.88 125.001 -264.26 130.291 -255.44 136.411C-246.28 142.761 -235.9 149.961 -216.03 149.961H-215.97C-196.1 149.961 -185.72 142.761 -176.56 136.411C-167.74 130.291 -160.12 125.001 -144.01 125.001C-127.88 125.001 -120.25 130.291 -111.42 136.411C-102.26 142.761 -91.88 149.961 -72 149.961C-52.12 149.961 -41.74 142.761 -32.58 136.411C-23.75 130.291 -16.12 125.001 0.0100098 125.001C16.12 125.001 23.7401 130.291 32.5601 136.411C41.7201 142.761 52.1001 149.961 71.9701 149.961H72.03C91.9 149.961 102.28 142.761 111.44 136.411C120.26 130.291 127.89 125.001 143.99 125.001C160.12 125.001 167.75 130.291 176.58 136.411C185.74 142.761 196.12 149.961 216 149.961C235.88 149.961 246.26 142.761 255.42 136.411C264.26 130.291 271.89 125.001 288.02 125.001V113.001C268.13 113.001 257.74 120.201 248.58 126.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 126.551C1679.81 132.671 1672.18 137.961 1656.06 137.961C1639.94 137.961 1632.31 132.671 1623.48 126.551C1614.32 120.201 1603.94 113.001 1584.06 113.001H1584.04C1564.16 113.001 1553.78 120.201 1544.62 126.551C1535.79 132.671 1528.17 137.961 1512.06 137.961C1495.95 137.961 1488.32 132.671 1479.5 126.551C1470.34 120.201 1459.96 113.001 1440.08 113.001H1440.06C1420.18 113.001 1409.8 120.201 1400.64 126.551C1391.81 132.671 1384.18 137.961 1368.06 137.961C1351.94 137.961 1344.31 132.671 1335.48 126.551C1326.32 120.201 1315.94 113.001 1296.06 113.001H1296.04C1276.17 113.001 1265.79 120.201 1256.63 126.551C1247.8 132.671 1240.17 137.961 1224.06 137.961C1207.95 137.961 1200.32 132.671 1191.49 126.551C1182.33 120.201 1171.95 113.001 1152.07 113.001H1152.06C1132.19 113.001 1121.8 120.201 1112.64 126.551C1103.81 132.671 1096.18 137.961 1080.06 137.961C1063.94 137.961 1056.31 132.671 1047.48 126.551C1038.32 120.201 1027.94 113.001 1008.06 113.001H1008.04C988.16 113.001 977.78 120.201 968.62 126.551C959.79 132.671 952.16 137.961 936.05 137.961C919.94 137.961 912.31 132.671 903.48 126.551C894.32 120.201 883.94 113.001 864.06 113.001H864.04C844.17 113.001 833.78 120.201 824.62 126.551C815.79 132.671 808.16 137.961 792.04 137.961C775.92 137.961 768.29 132.671 759.46 126.551C750.3 120.201 739.92 113.001 720.04 113.001H720.02C700.14 113.001 689.76 120.201 680.6 126.551C671.77 132.671 664.14 137.961 648.03 137.961C631.92 137.961 624.29 132.671 615.46 126.551C606.3 120.201 595.92 113.001 576.04 113.001H576.02C556.15 113.001 545.76 120.201 536.6 126.551C527.77 132.671 520.14 137.961 504.02 137.961C487.9 137.961 480.27 132.671 471.44 126.551C462.28 120.201 451.89 113.001 432.01 113.001C412.13 113.001 401.75 120.201 392.59 126.551C383.76 132.671 376.13 137.961 359.99 137.961C343.85 137.961 336.25 132.671 327.42 126.551C318.26 120.201 307.89 113.001 288.02 113.001V125.001C304.13 125.001 311.75 130.291 320.58 136.411C329.74 142.761 340.12 149.961 359.99 149.961C379.86 149.961 390.26 142.761 399.42 136.411C408.25 130.291 415.88 125.001 432 125.001C448.12 125.001 455.76 130.291 464.6 136.411C473.76 142.761 484.14 149.961 504.02 149.961C523.9 149.961 534.28 142.761 543.44 136.411C552.27 130.291 559.9 125.001 576.03 125.001C592.14 125.001 599.76 130.291 608.58 136.411C617.74 142.761 628.12 149.961 647.99 149.961H648.05C667.92 149.961 678.3 142.761 687.46 136.411C696.28 130.291 703.91 125.001 720.01 125.001C736.14 125.001 743.77 130.291 752.6 136.411C761.76 142.761 772.14 149.961 792.02 149.961C811.9 149.961 822.28 142.761 831.44 136.411C840.27 130.291 847.9 125.001 864.03 125.001C880.14 125.001 887.76 130.291 896.58 136.411C905.74 142.761 916.12 149.961 935.99 149.961H936.05C955.92 149.961 966.3 142.761 975.46 136.411C984.28 130.291 991.91 125.001 1008.01 125.001C1024.14 125.001 1031.77 130.291 1040.6 136.411C1049.76 142.761 1060.14 149.961 1080.02 149.961C1099.9 149.961 1110.28 142.761 1119.44 136.411C1128.27 130.291 1135.9 125.001 1152.03 125.001C1168.14 125.001 1175.76 130.291 1184.58 136.411C1193.74 142.761 1204.12 149.961 1223.99 149.961H1224.05C1243.92 149.961 1254.3 142.761 1263.46 136.411C1272.28 130.291 1279.9 125.001 1296.01 125.001C1312.14 125.001 1319.77 130.291 1328.6 136.411C1337.76 142.761 1348.14 149.961 1368.02 149.961C1387.9 149.961 1398.28 142.761 1407.44 136.411C1416.27 130.291 1423.9 125.001 1440.03 125.001C1456.14 125.001 1463.76 130.291 1472.58 136.411C1481.74 142.761 1492.12 149.961 1511.99 149.961H1512.05C1531.92 149.961 1542.3 142.761 1551.46 136.411C1560.28 130.291 1567.91 125.001 1584.01 125.001C1600.14 125.001 1607.77 130.291 1616.6 136.411C1625.76 142.761 1636.14 149.961 1656.02 149.961C1675.9 149.961 1686.28 142.761 1695.44 136.411C1704.28 130.291 1711.91 125.001 1728.04 125.001V113.001C1708.15 113.001 1697.76 120.201 1688.6 126.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n            <\/g>\n            <defs>\n                <clipPath id=\"clip0_1140_15955\">\n                    <rect width=\"576\" height=\"151\" fill=\"white\" transform=\"translate(0 0.000976562)\" \/>\n                <\/clipPath>\n            <\/defs>\n        <\/svg>\n                        <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"text_block\">\n                    <div class=\"txt_block_inner\">\n                        <h2><\/h2>\n                        <p>Le d\u00e9veloppement de la mobilit\u00e9 \u00e9lectrique s\u2019accompagne de l\u2019installation de bornes de recharge, y compris dans les immeubles d\u2019habitation collectifs. Une approche mutualis\u00e9e s\u2019impose comme une solution privil\u00e9gi\u00e9e, car elle permet d\u2019optimiser l\u2019alimentation \u00e9lectrique tout en facilitant une gestion centralis\u00e9e de la recharge. Cette strat\u00e9gie garantit un acc\u00e8s \u00e9quitable \u00e0 la recharge pour tous les r\u00e9sidents.<br \/>\nAfin d\u2019encourager les propri\u00e9taires \u00e0 adopter cette d\u00e9marche globale, la Commune, au travers de son programme de subvention \u00e9quiwatt, alloue une subvention cumulable \u00e0 la subvention cantonale pour l&#8217;infrastructure de recharge dans les b\u00e2timents collectifs.<\/p>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n \n\n<section class=\"only_icon_block no_bg\" id=\"Pourquoi-installer\">\n    <div class=\"sey_inner_page_container\">\n                <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"section_heading\">\n                                            <h1>Pourquoi opter pour des bornes intelligentes ?<\/h1>\n                                        <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"row\">\n            <div class=\"txt_block_inner\">\n                <h2>Les avantages<\/h2>\n                <p class=\"sub_title\"><\/p>\n                                <ul class=\"icon_list with_same_icon\">\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Garantir un acc\u00e8s \u00e9quitable \u00e0 la recharge pour tous les r\u00e9sidents<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Optimiser la recharge des v\u00e9hicules<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">R\u00e9duire les co\u00fbts collectivement <\/span>\n                                                    <\/div>\n                    <\/li>\n                                    <\/ul>\n                                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n  \n\n<section class=\"only_title_block\" id=\"montant-subvention\">\n    <div class=\"sey_inner_page_container\">\n        <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"section_heading\">\n                    <h1>Montant de la subvention<\/h1>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n        <section class=\"accordion_with_icon_header\" id=\"\">\n                    <div class=\"sey_inner_page_container\">\n                        <div class=\"row only_this\">\n                            <div class=\"col-sm-12 only_this\">\n                                <div class=\"acc_block_items\">\n                                                                                        <div class=\"acc_item\">\n                                                        <div class=\"acc_head\">\n                                                            <div class=\"inner\">\n                                                                <img decoding=\"async\" src=\"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto_bornes-recharge.webp\" alt=\"\">\n                                                                <h4>Subvention communale<\/h4>\n                                                            <\/div>\n                                                        <\/div>\n                                                        <div class=\"acc_body\">\n                                                                                                                               \n                                                                                                                                                                                                                                     <div class=\"inner_title\">\n                                                                                       Montant forfaitaire de CHF 600.- par point de recharge, max. CHF 6&#8217;000.- par immeuble                                                                                    <\/div>\n                                                                                    <div class=\"inner_sub_title\">\n                                                                                                                                                                        <\/div>\n                                                                                                                                                                                                                                                                                                                 \n                                                                                \n                                                                       \n                                                                                                                                       \n                                                                                                                                                                                                                                                                                                                                                                                             <div class=\"inner_title\">\n                                                                                                                                                                           <\/div>\n                                                                                    <div class=\"sey_cta_blocks\">\n                                                                                        <div class=\"block_title\">\n                                                                                            <span class=\"\"><\/span>\n                                                                                        <\/div>\n                                                                                        <div class=\"cta_row cta_col_3\">\n                                                                                                                                                                                                                                                                                                                        <div class=\"cta_col\">\n                                                                                                                        <div class=\"cta_item\">\n                                                                                                                            <a href=\"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/17.CG_Recharge-intelligente.pdf\" target=\"_blank\"><\/a>\n                                                                                                                            <div class=\"inner_row\">\n                                                                                                                                <div class=\"cta_text\">\n                                                                                                                                    <h3 class=\"cta_title\">Conditions g\u00e9n\u00e9rales<\/h3>\n                                                                                                                                    <p class=\"cta_txtss\"><\/p>\n                                                                                                                                <\/div>\n                                                                                                                                <div class=\"cta_btn\">\n                                                                                                                                    <span href=\"\"><svg width=\"16\" height=\"16\"\n                                                                                                                                            viewBox=\"0 0 16 16\" fill=\"none\"\n                                                                                                                                            xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                                                                                                            <path\n                                                                                                                                                d=\"M1.0101 6.9899C0.452237 6.9899 0 7.44214 0 8C0 8.55786 0.452238 9.0101 1.0101 9.0101H12.1212L7.28283 13.8485C6.88675 14.2446 6.88675 14.8867 7.28283 15.2828C7.67891 15.6789 8.32109 15.6789 8.71717 15.2828L15.2929 8.70711C15.6834 8.31658 15.6834 7.68342 15.2929 7.29289L8.71717 0.717171C8.32109 0.321088 7.67891 0.321089 7.28283 0.717172C6.88674 1.11325 6.88675 1.75543 7.28283 2.15152L12.1212 6.9899H1.0101Z\" \/>\n                                                                                                                                        <\/svg><\/span>\n                                                                                                                                <\/div>\n                                                                                                                            <\/div>\n                                                                                                                        <\/div>\n                                                                                                                    <\/div>\n                                                                                                                                                                                                                                                                                                        <\/div>\n                                                                                    <\/div>\n                                                                                                                                                         \n                                                                                \n                                                                       \n                                                                                                                         <\/div>\n                                                    <\/div>\n                                                                                                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/section>\n                \n\n<section class=\"only_icon_block no_bg\" id=\"demarches\">\n    <div class=\"sey_inner_page_container\">\n                <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"section_heading\">\n                                            <h1>Recommandations pour les propri\u00e9taires<\/h1>\n                                        <\/div>\n            <\/div>\n        <\/div>\n                <div class=\"row\">\n            <div class=\"txt_block_inner\">\n                <h2>Les \u00e9tapes<\/h2>\n                <p class=\"sub_title\"><\/p>\n                                <ul class=\"icon_list single_column with_same_icon\">\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Anticiper l\u2019installation de borne de recharge et \u00e9valuer les besoins<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Etudier la faisabilit\u00e9 et \u00e9valuer la capacit\u00e9 \u00e9lectrique de l\u2019immeuble<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Planifier l\u2019installation de mani\u00e8re collective<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Demander plusieurs offres<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">R\u00e9aliser les travaux<\/span>\n                                                    <\/div>\n                    <\/li>\n                                        <li><img decoding=\"async\" src=\"\" alt=\"\">\n                        <div class=\"txts\"><span class=\"title\">Remplissez le formulaire de demande de subvention communale ci-apr\u00e8s<\/span>\n                                                    <\/div>\n                    <\/li>\n                                    <\/ul>\n                                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n  \n\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n<section class=\"gravity_form_section\">\n\t<div class=\"sey_inner_page_container\">\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_66' ><style>#gform_wrapper_66[data-form-index=\"0\"].gform-theme{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg width='640' height='640' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-btn-bg-color-hover-tertiary: #EBEBEB;--gf-field-img-choice-size: var(--gf-field-img-choice-size-md);--gf-field-img-choice-card-space: var(--gf-field-img-choice-card-space-md);--gf-field-img-choice-check-ind-size: var(--gf-field-img-choice-check-ind-size-md);--gf-field-img-choice-check-ind-icon-size: var(--gf-field-img-choice-check-ind-icon-size-md);--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_66' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n                            <h2 class=\"gform_title\">Subvention Borne de recharge intelligente<\/h2>\n                            <p class='gform_description'><\/p>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; indicates required fields<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_66'  action='\/pt\/wp-json\/wp\/v2\/programes\/13041#gf_66' data-formid='66' novalidate>\n        <div id='gf_progressbar_wrapper_66' class='gf_progressbar_wrapper' data-start-at-zero=''>\n        \t<p class=\"gf_progressbar_title\">Step <span class='gf_step_current_page'>1<\/span> of <span class='gf_step_page_count'>5<\/span><span class='gf_step_page_name'> - Informations personnelles (b\u00e9n\u00e9ficiaire)<\/span>\n        \t<\/p>\n            <div class='gf_progressbar gf_progressbar_custom' aria-hidden='true'>\n                <div class='gf_progressbar_percentage percentbar_custom percentbar_20' style='width:20%; color:#FFFFFF; background-color:#0c99a3;'><span>20%<\/span><\/div>\n            <\/div><\/div>\n                        <div class='gform-body gform_body'><div id='gform_page_66_1' class='gform_page ' data-js='page-field-id-0' >\n\t\t\t\t\t<div class='gform_page_fields'><div id='gform_fields_66' class='gform_fields top_label form_sublabel_below description_below validation_below'><fieldset id=\"field_66_6\" class=\"gfield gfield--type-radio gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><legend class='gfield_label gform-field-label' ><span class='gform-field-label__text'>Civilit\u00e9<\/span><\/legend><div class='ginput_container ginput_container_radio'><div class='gfield_radio' id='input_66_6'>\n\t\t\t<div class='gchoice gchoice_66_6_0'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_6' type='radio' value='Madame'  id='choice_66_6_0' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_66_6_0' id='label_66_6_0' class='gform-field-label gform-field-label--type-inline'>Madame<\/label>\n\t\t\t<\/div>\n\t\t\t<div class='gchoice gchoice_66_6_1'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_6' type='radio' value='Monsieur'  id='choice_66_6_1' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_66_6_1' id='label_66_6_1' class='gform-field-label gform-field-label--type-inline'>Monsieur<\/label>\n\t\t\t<\/div>\n\t\t\t<div class='gchoice gchoice_66_6_2'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_6' type='radio' value='Autre'  id='choice_66_6_2' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_66_6_2' id='label_66_6_2' class='gform-field-label gform-field-label--type-inline'>Autre<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><fieldset id=\"field_66_7\" class=\"gfield gfield--type-name gfield--input-type-name gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Identit\u00e9<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_66_7'>\n                            \n                            <span id='input_66_7_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_7.3' id='input_66_7_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_66_7_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_66_7_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_7.6' id='input_66_7_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_66_7_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><fieldset id=\"field_66_8\" class=\"gfield gfield--type-address gfield--input-type-address gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Adresse<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_city has_zip ginput_container_address gform-grid-row' id='input_66_8' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_66_8_1_container' >\n                                        <input type='text' name='input_8.1' id='input_66_8_1' value=''    aria-required='true'    \/>\n                                        <label for='input_66_8_1' id='input_66_8_1_label' class='gform-field-label gform-field-label--type-sub '>Street Address<\/label>\n                                    <\/span><span class='ginput_left address_city ginput_address_city gform-grid-col' id='input_66_8_3_container' >\n                                    <input type='text' name='input_8.3' id='input_66_8_3' value=''    aria-required='true'    \/>\n                                    <label for='input_66_8_3' id='input_66_8_3_label' class='gform-field-label gform-field-label--type-sub '>Localit\u00e9<\/label>\n                                 <\/span><input type='hidden' class='gform_hidden' name='input_8.4' id='input_66_8_4' value=''\/><span class='ginput_right address_zip ginput_address_zip gform-grid-col' id='input_66_8_5_container' >\n                                    <input type='text' name='input_8.5' id='input_66_8_5' value=''    aria-required='true'    \/>\n                                    <label for='input_66_8_5' id='input_66_8_5_label' class='gform-field-label gform-field-label--type-sub '>NPA<\/label>\n                                <\/span><input type='hidden' class='gform_hidden' name='input_8.6' id='input_66_8_6' value='' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><div id=\"field_66_9\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--phone-format-international gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_9'><span class='gform-field-label__text'>T\u00e9l\u00e9phone<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_9' id='input_66_9' type='tel' value='' class='medium'   aria-required=\"true\" aria-invalid=\"false\"    \/><\/div><\/div><div id=\"field_66_10\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_10'><span class='gform-field-label__text'>E-mail<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_10' id='input_66_10' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                         <button type='button' id='gform_next_button_66_1' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' >Suivant<\/button> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_66_2' class='gform_page' data-js='page-field-id-1' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_66_2' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_66_11\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_11'><span class='gform-field-label__text'>Soci\u00e9t\u00e9<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_11' id='input_66_11' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <button type='button' id='gform_previous_button_66_3' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' >Pr\u00e9c\u00e9dent<\/button> <button type='button' id='gform_next_button_66_3' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' >Suivant<\/button> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_66_3' class='gform_page' data-js='page-field-id-3' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_66_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><fieldset id=\"field_66_27\" class=\"gfield gfield--type-radio gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><legend class='gfield_label gform-field-label' ><span class='gform-field-label__text'>Habitat collectif<\/span><\/legend><div class='ginput_container ginput_container_radio'><div class='gfield_radio' id='input_66_27'>\n\t\t\t<div class='gchoice gchoice_66_27_0'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_27' type='radio' value='Oui'  id='choice_66_27_0' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_66_27_0' id='label_66_27_0' class='gform-field-label gform-field-label--type-inline'>Oui<\/label>\n\t\t\t<\/div>\n\t\t\t<div class='gchoice gchoice_66_27_1'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_27' type='radio' value='Non'  id='choice_66_27_1' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_66_27_1' id='label_66_27_1' class='gform-field-label gform-field-label--type-inline'>Non<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_66_24\" class=\"gfield gfield--type-number gfield--input-type-number gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_24'><span class='gform-field-label__text'>Nombre de logements<\/span><\/label><div class='ginput_container ginput_container_number'><input name='input_24' id='input_66_24' type='number' step='any' min='2'  value='' class='small'      aria-invalid=\"false\" aria-describedby=\"gfield_instruction_66_24\" \/><div class='gfield_description instruction ' id='gfield_instruction_66_24'>Please enter a number greater than or equal to <strong>2<\/strong>.<\/div><\/div><\/div><div id=\"field_66_26\" class=\"gfield gfield--type-number gfield--input-type-number gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_26'><span class='gform-field-label__text'>Nombre de points de recharge<\/span><\/label><div class='ginput_container ginput_container_number'><input name='input_26' id='input_66_26' type='number' step='any' min='2'  value='' class='small'      aria-invalid=\"false\" aria-describedby=\"gfield_instruction_66_26\" \/><div class='gfield_description instruction ' id='gfield_instruction_66_26'>Please enter a number greater than or equal to <strong>2<\/strong>.<\/div><\/div><\/div><div id=\"field_66_25\" class=\"gfield gfield--type-number gfield--input-type-number gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_25'><span class='gform-field-label__text'>Nombre de places de parc total du b\u00e2timent (int\u00e9rieures et ext\u00e9rieures)<\/span><\/label><div class='ginput_container ginput_container_number'><input name='input_25' id='input_66_25' type='number' step='any' min='2'  value='' class='small'      aria-invalid=\"false\" aria-describedby=\"gfield_instruction_66_25\" \/><div class='gfield_description instruction ' id='gfield_instruction_66_25'>Please enter a number greater than or equal to <strong>2<\/strong>.<\/div><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <button type='button' id='gform_previous_button_66_4' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' >Pr\u00e9c\u00e9dent<\/button> <button type='button' id='gform_next_button_66_4' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' >Suivant<\/button> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_66_4' class='gform_page' data-js='page-field-id-4' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_66_4' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_66_13\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_13'><span class='gform-field-label__text'>IBAN<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_13' id='input_66_13' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_66_15\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_66_15'><span class='gform-field-label__text'>Titulaire du compte<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_15' id='input_66_15' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <button type='button' id='gform_previous_button_66_21' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' >Pr\u00e9c\u00e9dent<\/button> <button type='button' id='gform_next_button_66_21' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' >Suivant<\/button> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_66_5' class='gform_page' data-js='page-field-id-21' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_66_5' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_66_22\" class=\"gfield gfield--type-fileupload gfield--input-type-fileupload gfield--width-full gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='gform_browse_button_66_22'><span class='gform-field-label__text'>Annexes<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_fileupload'><div id='gform_multifile_upload_66_22' data-settings='{&quot;runtimes&quot;:&quot;html5,flash,html4&quot;,&quot;browse_button&quot;:&quot;gform_browse_button_66_22&quot;,&quot;container&quot;:&quot;gform_multifile_upload_66_22&quot;,&quot;drop_element&quot;:&quot;gform_drag_drop_area_66_22&quot;,&quot;filelist&quot;:&quot;gform_preview_66_22&quot;,&quot;unique_names&quot;:true,&quot;file_data_name&quot;:&quot;file&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/?gf_page=3ef248413b60666&quot;,&quot;flash_swf_url&quot;:&quot;https:\\\/\\\/www.yverdon-energies.ch\\\/wp-includes\\\/js\\\/plupload\\\/plupload.flash.swf&quot;,&quot;silverlight_xap_url&quot;:&quot;https:\\\/\\\/www.yverdon-energies.ch\\\/wp-includes\\\/js\\\/plupload\\\/plupload.silverlight.xap&quot;,&quot;filters&quot;:{&quot;mime_types&quot;:[{&quot;title&quot;:&quot;Allowed Files&quot;,&quot;extensions&quot;:&quot;*&quot;}],&quot;max_file_size&quot;:&quot;314572800b&quot;},&quot;multipart&quot;:true,&quot;urlstream_upload&quot;:false,&quot;multipart_params&quot;:{&quot;form_id&quot;:66,&quot;field_id&quot;:22,&quot;_gform_file_upload_nonce_66_22&quot;:&quot;4be49398d7&quot;},&quot;gf_vars&quot;:{&quot;max_files&quot;:0,&quot;message_id&quot;:&quot;gform_multifile_messages_66_22&quot;,&quot;disallowed_extensions&quot;:[&quot;php&quot;,&quot;asp&quot;,&quot;aspx&quot;,&quot;cmd&quot;,&quot;csh&quot;,&quot;bat&quot;,&quot;html&quot;,&quot;htm&quot;,&quot;hta&quot;,&quot;jar&quot;,&quot;exe&quot;,&quot;com&quot;,&quot;js&quot;,&quot;lnk&quot;,&quot;htaccess&quot;,&quot;phar&quot;,&quot;phtml&quot;,&quot;ps1&quot;,&quot;ps2&quot;,&quot;php3&quot;,&quot;php4&quot;,&quot;php5&quot;,&quot;php6&quot;,&quot;py&quot;,&quot;rb&quot;,&quot;tmp&quot;]}}' class='gform_fileupload_multifile'>\n\t\t\t\t\t\t\t\t\t\t<div id='gform_drag_drop_area_66_22' class='gform_drop_area gform-theme-field-control'>\n\t\t\t\t\t\t\t\t\t\t\t<span class='gform_drop_instructions'>Drop files here or <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<button type='button' id='gform_browse_button_66_22' class='button gform_button_select_files gform-theme-button gform-theme-button--control' aria-describedby=\"gfield_upload_rules_66_22 gfield_description_66_22\"  >Select files<\/button>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><span class='gfield_description gform_fileupload_rules' id='gfield_upload_rules_66_22'>Max. file size: 300 MB.<\/span><ul class='validation_message--hidden-on-empty gform-ul-reset' id='gform_multifile_messages_66_22'><\/ul> <div id='gform_preview_66_22' class='ginput_preview_list'><\/div><\/div><div class='gfield_description' id='gfield_description_66_22'>- Une copie de l\u2019offre de l\u2019installation compl\u00e8te retenue (devis)<br>\n- La fiche technique de la borne de recharge comprenant un syst\u00e8me de gestion centralis\u00e9e de la recharge et des pics de charge (statique ou dynamique)<br>\n- Une copie de la facture (la facture doit imp\u00e9rativement indiquer le nombre de points de recharge intall\u00e9s)<br>\n- Une preuve de paiement pour les travaux (facture acquitt\u00e9e ou relev\u00e9 bancaire).\n<\/div><\/div><fieldset id=\"field_66_19\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gfield--choice-align-vertical\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' ><span class='gform-field-label__text'>Conditions<\/span><span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_19.1' id='input_66_19_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_66_19_1' ><span class='gform-field-label__text'>J'ai lu et j'accepte les condition pour l'attribution de subvention<\/span><\/label><input type='hidden' name='input_19.2' value='J&#039;ai lu et j&#039;accepte les condition pour l&#039;attribution de subvention' class='gform_hidden' \/><input type='hidden' name='input_19.3' value='1' class='gform_hidden' \/><\/div><\/fieldset><\/div><\/div>\n        <div class='gform-page-footer gform_page_footer top_label'><button type='submit' id='gform_previous_button_66' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' >Pr\u00e9c\u00e9dent<\/button> <button type='submit' id='gform_submit_button_66' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' >Envoyer<\/button> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_66' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_66' id='gform_theme_66' value='orbital' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_66' id='gform_style_settings_66' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_66' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='66' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='tLJ5T7Uj+9a94ry+gn+RNP0wRf2mg3XZnIYaGYtfUYet2+bvSDHDSoADqYitlYOLHvZb88UlbTb5td9DVC+R6M6BWGgUsjCRzpiLAvMdhLXjaVA=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_66' value='WyJ7XCI2XCI6W1wiZDkwOTk2ZTJhMTVhYThiYWM3ODgzYzRjNTUxMWRjZGJcIixcImE1NDFmNjUyYjAwNTM4MDU0ZWYxNmNkMGNmZjBhNmM0XCIsXCI5ODIwM2M2YzU5YzRiOTc3ZWY3ZmQwNTY4Y2NmYmExM1wiXSxcIjI3XCI6W1wiN2E0NmM3YmVhNjJmYThmOGNhMTJhN2Q5MGEyZjYxMjZcIixcIjE0NmMxZmQ0NGNlZDA5YWQzOTI0NDY0Y2RmZDEwN2MwXCJdLFwiMTkuMVwiOlwiYWRhMGU3MDVlM2NhNzMxNmQwNGZjOTAxNTk0ZWNkZGZcIixcIjE5LjJcIjpcIjRmNDIzNjMwYmVkYmFhMzk4ZThkMDliZWNiNjY4MGQwXCIsXCIxOS4zXCI6XCJhZGEwZTcwNWUzY2E3MzE2ZDA0ZmM5MDE1OTRlY2RkZlwiLFwiZ2Zvcm1fc3VibWlzc2lvbl9tZXRob2RcIjpbXCI4OTJkMDJiNjQ4OTE3ZDA2ZjEyOWUzZTVlMDVlNzNlY1wiLFwiNDA5MzFkYjcwNTgyZjc4Y2U5NGU0YTI0ZTYxMGFlODdcIl0sXCJnZm9ybV90aGVtZVwiOlwiZDk5NjEwODk3M2IxMGI3NjUyYjkzNjMyMzU3MzZhYzBcIixcImdmb3JtX3N0eWxlX3NldHRpbmdzXCI6XCJlYWNkZDhjODQxMTE0YzYxMjMzN2U1OTM1MDVkZTVmM1wiLFwiZm9ybV9pZFwiOlwiZDAzNzJlNDk4Nzc3OWY5YjVmMTUyOGY2YTA2NGVjOGNcIixcInVybFwiOlwiYWU2MjU1NGJiODI2Zjc0ZjU0NzhmZWJiMDVlODkyYTBcIixcInN0YXRlX3RpbWVzdGFtcFwiOlwiYjdmODA0YzE5ZDE3MTdiMzBiNGNhMGRkZjkwOGNmNzJcIn0iLCI3ODlkMzVkYmUwNDFlMjRhZGQxMmJjYWI1NjA3NDJiZiIsMTc4ODMzNDE3OV0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_66' id='gform_target_page_number_66' value='2' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_66' id='gform_source_page_number_66' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            <input type='hidden' name='gform_uploaded_files' id='gform_uploaded_files_66' value='' \/>\n        <\/div>\n             <\/div><\/div>\n                        <\/form>\n                        <\/div><\/div><\/section>\n\n\n<section class=\"pdf_btns_block_with_text no_bg\" id=\"\">\n    <div class=\"sey_inner_page_container\">\n        <div class=\"row\">\n            <div class=\"col-sm-12\">\n                  <div class=\"pdf_btn_col mb_0\">\n                    <div class=\"txt_block\">\n                        <h2 class=\"block_capt\"><\/h2>\n                        <p><\/p>\n\n                    <\/div>\n                                            <div class=\"pdf_btns_block\">\n                                                            <div class=\"btn_col\">\n                                    <a href=\"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/17.CG_Recharge-intelligente.pdf\" class=\"pdf_btn\">\n                                        <div class=\"img_box\">\n                                            <img decoding=\"async\" src=\"#\" alt=\"\">\n                                            <img decoding=\"async\" src=\"#\" alt=\"\">\n                                        <\/div>\n                                        <span>Conditions g\u00e9n\u00e9rales<\/span>\n                                    <\/a>\n                                <\/div>\n                                                        <\/div>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text_with_wave no_bg\" id=\"plus-informations\">\n    <div class=\"sey_inner_page_container\">\n        <svg width=\"488\" height=\"151\" viewBox=\"0 0 488 151\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n            class=\"wv_lp\">\n            <g clip-path=\"url(#clip0_1140_15955)\">\n                <path\n                    d=\"M248.62 15.551C239.79 21.671 232.16 26.961 216.04 26.961C199.92 26.961 192.29 21.671 183.46 15.551C174.3 9.20098 163.92 2.00098 144.04 2.00098H144.02C124.14 2.00098 113.76 9.20098 104.6 15.551C95.7701 21.671 88.15 26.961 72.04 26.961C55.9301 26.961 48.2999 21.671 39.48 15.551C30.3199 9.20098 19.9401 2.00098 0.0600586 2.00098H0.0400391C-19.84 2.00098 -30.22 9.20098 -39.38 15.551C-48.21 21.671 -55.84 26.961 -71.96 26.961C-88.08 26.961 -95.71 21.671 -104.54 15.551C-113.7 9.20098 -124.08 2.00098 -143.96 2.00098H-143.98C-163.85 2.00098 -174.23 9.20098 -183.39 15.551C-192.22 21.671 -199.85 26.961 -215.96 26.961C-232.07 26.961 -239.7 21.671 -248.53 15.551C-257.69 9.20098 -268.07 2.00098 -287.95 2.00098H-287.96C-307.83 2.00098 -318.22 9.20098 -327.38 15.551C-336.21 21.671 -343.84 26.961 -359.96 26.961C-376.08 26.961 -383.71 21.671 -392.54 15.551C-401.7 9.20098 -412.08 2.00098 -431.96 2.00098H-431.98C-451.86 2.00098 -462.24 9.20098 -471.4 15.551C-480.23 21.671 -487.86 26.961 -503.97 26.961C-520.08 26.961 -527.71 21.671 -536.54 15.551C-545.7 9.20098 -556.08 2.00098 -575.96 2.00098H-575.98C-595.85 2.00098 -606.24 9.20098 -615.4 15.551C-624.23 21.671 -631.86 26.961 -647.98 26.961C-664.1 26.961 -671.73 21.671 -680.56 15.551C-689.72 9.20098 -700.1 2.00098 -719.98 2.00098H-720C-739.88 2.00098 -750.26 9.20098 -759.42 15.551C-768.25 21.671 -775.88 26.961 -791.99 26.961C-808.1 26.961 -815.73 21.671 -824.56 15.551C-833.72 9.20098 -844.1 2.00098 -863.98 2.00098H-864C-883.87 2.00098 -894.26 9.20098 -903.42 15.551C-912.25 21.671 -919.88 26.961 -936 26.961C-952.12 26.961 -959.75 21.671 -968.58 15.551C-977.74 9.20098 -988.13 2.00098 -1008.01 2.00098C-1027.89 2.00098 -1038.27 9.20098 -1047.43 15.551C-1056.26 21.671 -1063.89 26.961 -1080.03 26.961C-1096.17 26.961 -1103.77 21.671 -1112.6 15.551C-1121.76 9.20098 -1132.13 2.00098 -1152 2.00098V14.001C-1135.89 14.001 -1128.27 19.291 -1119.44 25.411C-1110.28 31.761 -1099.9 38.961 -1080.03 38.961C-1060.16 38.961 -1049.76 31.761 -1040.6 25.411C-1031.77 19.291 -1024.14 14.001 -1008.02 14.001C-991.9 14.001 -984.26 19.291 -975.42 25.411C-966.26 31.761 -955.88 38.961 -936 38.961C-916.12 38.961 -905.74 31.761 -896.58 25.411C-887.75 19.291 -880.12 14.001 -863.99 14.001C-847.88 14.001 -840.26 19.291 -831.44 25.411C-822.28 31.761 -811.9 38.961 -792.03 38.961H-791.97C-772.1 38.961 -761.72 31.761 -752.56 25.411C-743.74 19.291 -736.11 14.001 -720.01 14.001C-703.88 14.001 -696.25 19.291 -687.42 25.411C-678.26 31.761 -667.88 38.961 -648 38.961C-628.12 38.961 -617.74 31.761 -608.58 25.411C-599.75 19.291 -592.12 14.001 -575.99 14.001C-559.88 14.001 -552.26 19.291 -543.44 25.411C-534.28 31.761 -523.9 38.961 -504.03 38.961H-503.97C-484.1 38.961 -473.72 31.761 -464.56 25.411C-455.74 19.291 -448.11 14.001 -432.01 14.001C-415.88 14.001 -408.25 19.291 -399.42 25.411C-390.26 31.761 -379.88 38.961 -360 38.961C-340.12 38.961 -329.74 31.761 -320.58 25.411C-311.75 19.291 -304.12 14.001 -287.99 14.001C-271.88 14.001 -264.26 19.291 -255.44 25.411C-246.28 31.761 -235.9 38.961 -216.03 38.961H-215.97C-196.1 38.961 -185.72 31.761 -176.56 25.411C-167.74 19.291 -160.12 14.001 -144.01 14.001C-127.88 14.001 -120.25 19.291 -111.42 25.411C-102.26 31.761 -91.88 38.961 -72 38.961C-52.12 38.961 -41.74 31.761 -32.58 25.411C-23.75 19.291 -16.12 14.001 0.0100098 14.001C16.12 14.001 23.7401 19.291 32.5601 25.411C41.7201 31.761 52.1001 38.961 71.9701 38.961H72.03C91.9 38.961 102.28 31.761 111.44 25.411C120.26 19.291 127.89 14.001 143.99 14.001C160.12 14.001 167.75 19.291 176.58 25.411C185.74 31.761 196.12 38.961 216 38.961C235.88 38.961 246.26 31.761 255.42 25.411C264.26 19.291 271.89 14.001 288.02 14.001V2.00098C268.13 2.00098 257.74 9.20098 248.58 15.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 15.551C1679.81 21.671 1672.18 26.961 1656.06 26.961C1639.94 26.961 1632.31 21.671 1623.48 15.551C1614.32 9.20098 1603.94 2.00098 1584.06 2.00098H1584.04C1564.16 2.00098 1553.78 9.20098 1544.62 15.551C1535.79 21.671 1528.17 26.961 1512.06 26.961C1495.95 26.961 1488.32 21.671 1479.5 15.551C1470.34 9.20098 1459.96 2.00098 1440.08 2.00098H1440.06C1420.18 2.00098 1409.8 9.20098 1400.64 15.551C1391.81 21.671 1384.18 26.961 1368.06 26.961C1351.94 26.961 1344.31 21.671 1335.48 15.551C1326.32 9.20098 1315.94 2.00098 1296.06 2.00098H1296.04C1276.17 2.00098 1265.79 9.20098 1256.63 15.551C1247.8 21.671 1240.17 26.961 1224.06 26.961C1207.95 26.961 1200.32 21.671 1191.49 15.551C1182.33 9.20098 1171.95 2.00098 1152.07 2.00098H1152.06C1132.19 2.00098 1121.8 9.20098 1112.64 15.551C1103.81 21.671 1096.18 26.961 1080.06 26.961C1063.94 26.961 1056.31 21.671 1047.48 15.551C1038.32 9.20098 1027.94 2.00098 1008.06 2.00098H1008.04C988.16 2.00098 977.78 9.20098 968.62 15.551C959.79 21.671 952.16 26.961 936.05 26.961C919.94 26.961 912.31 21.671 903.48 15.551C894.32 9.20098 883.94 2.00098 864.06 2.00098H864.04C844.17 2.00098 833.78 9.20098 824.62 15.551C815.79 21.671 808.16 26.961 792.04 26.961C775.92 26.961 768.29 21.671 759.46 15.551C750.3 9.20098 739.92 2.00098 720.04 2.00098H720.02C700.14 2.00098 689.76 9.20098 680.6 15.551C671.77 21.671 664.14 26.961 648.03 26.961C631.92 26.961 624.29 21.671 615.46 15.551C606.3 9.20098 595.92 2.00098 576.04 2.00098H576.02C556.15 2.00098 545.76 9.20098 536.6 15.551C527.77 21.671 520.14 26.961 504.02 26.961C487.9 26.961 480.27 21.671 471.44 15.551C462.28 9.20098 451.89 2.00098 432.01 2.00098C412.13 2.00098 401.75 9.20098 392.59 15.551C383.76 21.671 376.13 26.961 359.99 26.961C343.85 26.961 336.25 21.671 327.42 15.551C318.26 9.20098 307.89 2.00098 288.02 2.00098V14.001C304.13 14.001 311.75 19.291 320.58 25.411C329.74 31.761 340.12 38.961 359.99 38.961C379.86 38.961 390.26 31.761 399.42 25.411C408.25 19.291 415.88 14.001 432 14.001C448.12 14.001 455.76 19.291 464.6 25.411C473.76 31.761 484.14 38.961 504.02 38.961C523.9 38.961 534.28 31.761 543.44 25.411C552.27 19.291 559.9 14.001 576.03 14.001C592.14 14.001 599.76 19.291 608.58 25.411C617.74 31.761 628.12 38.961 647.99 38.961H648.05C667.92 38.961 678.3 31.761 687.46 25.411C696.28 19.291 703.91 14.001 720.01 14.001C736.14 14.001 743.77 19.291 752.6 25.411C761.76 31.761 772.14 38.961 792.02 38.961C811.9 38.961 822.28 31.761 831.44 25.411C840.27 19.291 847.9 14.001 864.03 14.001C880.14 14.001 887.76 19.291 896.58 25.411C905.74 31.761 916.12 38.961 935.99 38.961H936.05C955.92 38.961 966.3 31.761 975.46 25.411C984.28 19.291 991.91 14.001 1008.01 14.001C1024.14 14.001 1031.77 19.291 1040.6 25.411C1049.76 31.761 1060.14 38.961 1080.02 38.961C1099.9 38.961 1110.28 31.761 1119.44 25.411C1128.27 19.291 1135.9 14.001 1152.03 14.001C1168.14 14.001 1175.76 19.291 1184.58 25.411C1193.74 31.761 1204.12 38.961 1223.99 38.961H1224.05C1243.92 38.961 1254.3 31.761 1263.46 25.411C1272.28 19.291 1279.9 14.001 1296.01 14.001C1312.14 14.001 1319.77 19.291 1328.6 25.411C1337.76 31.761 1348.14 38.961 1368.02 38.961C1387.9 38.961 1398.28 31.761 1407.44 25.411C1416.27 19.291 1423.9 14.001 1440.03 14.001C1456.14 14.001 1463.76 19.291 1472.58 25.411C1481.74 31.761 1492.12 38.961 1511.99 38.961H1512.05C1531.92 38.961 1542.3 31.761 1551.46 25.411C1560.28 19.291 1567.91 14.001 1584.01 14.001C1600.14 14.001 1607.77 19.291 1616.6 25.411C1625.76 31.761 1636.14 38.961 1656.02 38.961C1675.9 38.961 1686.28 31.761 1695.44 25.411C1704.28 19.291 1711.91 14.001 1728.04 14.001V2.00098C1708.15 2.00098 1697.76 9.20098 1688.6 15.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 52.551C239.79 58.671 232.16 63.961 216.04 63.961C199.92 63.961 192.29 58.671 183.46 52.551C174.3 46.201 163.92 39.001 144.04 39.001H144.02C124.14 39.001 113.76 46.201 104.6 52.551C95.7701 58.671 88.15 63.961 72.04 63.961C55.9301 63.961 48.2999 58.671 39.48 52.551C30.3199 46.201 19.9401 39.001 0.0600586 39.001H0.0400391C-19.84 39.001 -30.22 46.201 -39.38 52.551C-48.21 58.671 -55.84 63.961 -71.96 63.961C-88.08 63.961 -95.71 58.671 -104.54 52.551C-113.7 46.201 -124.08 39.001 -143.96 39.001H-143.98C-163.85 39.001 -174.23 46.201 -183.39 52.551C-192.22 58.671 -199.85 63.961 -215.96 63.961C-232.07 63.961 -239.7 58.671 -248.53 52.551C-257.69 46.201 -268.07 39.001 -287.95 39.001H-287.96C-307.83 39.001 -318.22 46.201 -327.38 52.551C-336.21 58.671 -343.84 63.961 -359.96 63.961C-376.08 63.961 -383.71 58.671 -392.54 52.551C-401.7 46.201 -412.08 39.001 -431.96 39.001H-431.98C-451.86 39.001 -462.24 46.201 -471.4 52.551C-480.23 58.671 -487.86 63.961 -503.97 63.961C-520.08 63.961 -527.71 58.671 -536.54 52.551C-545.7 46.201 -556.08 39.001 -575.96 39.001H-575.98C-595.85 39.001 -606.24 46.201 -615.4 52.551C-624.23 58.671 -631.86 63.961 -647.98 63.961C-664.1 63.961 -671.73 58.671 -680.56 52.551C-689.72 46.201 -700.1 39.001 -719.98 39.001H-720C-739.88 39.001 -750.26 46.201 -759.42 52.551C-768.25 58.671 -775.88 63.961 -791.99 63.961C-808.1 63.961 -815.73 58.671 -824.56 52.551C-833.72 46.201 -844.1 39.001 -863.98 39.001H-864C-883.87 39.001 -894.26 46.201 -903.42 52.551C-912.25 58.671 -919.88 63.961 -936 63.961C-952.12 63.961 -959.75 58.671 -968.58 52.551C-977.74 46.201 -988.13 39.001 -1008.01 39.001C-1027.89 39.001 -1038.27 46.201 -1047.43 52.551C-1056.26 58.671 -1063.89 63.961 -1080.03 63.961C-1096.17 63.961 -1103.77 58.671 -1112.6 52.551C-1121.76 46.201 -1132.13 39.001 -1152 39.001V51.001C-1135.89 51.001 -1128.27 56.291 -1119.44 62.411C-1110.28 68.761 -1099.9 75.961 -1080.03 75.961C-1060.16 75.961 -1049.76 68.761 -1040.6 62.411C-1031.77 56.291 -1024.14 51.001 -1008.02 51.001C-991.9 51.001 -984.26 56.291 -975.42 62.411C-966.26 68.761 -955.88 75.961 -936 75.961C-916.12 75.961 -905.74 68.761 -896.58 62.411C-887.75 56.291 -880.12 51.001 -863.99 51.001C-847.88 51.001 -840.26 56.291 -831.44 62.411C-822.28 68.761 -811.9 75.961 -792.03 75.961H-791.97C-772.1 75.961 -761.72 68.761 -752.56 62.411C-743.74 56.291 -736.11 51.001 -720.01 51.001C-703.88 51.001 -696.25 56.291 -687.42 62.411C-678.26 68.761 -667.88 75.961 -648 75.961C-628.12 75.961 -617.74 68.761 -608.58 62.411C-599.75 56.291 -592.12 51.001 -575.99 51.001C-559.88 51.001 -552.26 56.291 -543.44 62.411C-534.28 68.761 -523.9 75.961 -504.03 75.961H-503.97C-484.1 75.961 -473.72 68.761 -464.56 62.411C-455.74 56.291 -448.11 51.001 -432.01 51.001C-415.88 51.001 -408.25 56.291 -399.42 62.411C-390.26 68.761 -379.88 75.961 -360 75.961C-340.12 75.961 -329.74 68.761 -320.58 62.411C-311.75 56.291 -304.12 51.001 -287.99 51.001C-271.88 51.001 -264.26 56.291 -255.44 62.411C-246.28 68.761 -235.9 75.961 -216.03 75.961H-215.97C-196.1 75.961 -185.72 68.761 -176.56 62.411C-167.74 56.291 -160.12 51.001 -144.01 51.001C-127.88 51.001 -120.25 56.291 -111.42 62.411C-102.26 68.761 -91.88 75.961 -72 75.961C-52.12 75.961 -41.74 68.761 -32.58 62.411C-23.75 56.291 -16.12 51.001 0.0100098 51.001C16.12 51.001 23.7401 56.291 32.5601 62.411C41.7201 68.761 52.1001 75.961 71.9701 75.961H72.03C91.9 75.961 102.28 68.761 111.44 62.411C120.26 56.291 127.89 51.001 143.99 51.001C160.12 51.001 167.75 56.291 176.58 62.411C185.74 68.761 196.12 75.961 216 75.961C235.88 75.961 246.26 68.761 255.42 62.411C264.26 56.291 271.89 51.001 288.02 51.001V39.001C268.13 39.001 257.74 46.201 248.58 52.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 52.551C1679.81 58.671 1672.18 63.961 1656.06 63.961C1639.94 63.961 1632.31 58.671 1623.48 52.551C1614.32 46.201 1603.94 39.001 1584.06 39.001H1584.04C1564.16 39.001 1553.78 46.201 1544.62 52.551C1535.79 58.671 1528.17 63.961 1512.06 63.961C1495.95 63.961 1488.32 58.671 1479.5 52.551C1470.34 46.201 1459.96 39.001 1440.08 39.001H1440.06C1420.18 39.001 1409.8 46.201 1400.64 52.551C1391.81 58.671 1384.18 63.961 1368.06 63.961C1351.94 63.961 1344.31 58.671 1335.48 52.551C1326.32 46.201 1315.94 39.001 1296.06 39.001H1296.04C1276.17 39.001 1265.79 46.201 1256.63 52.551C1247.8 58.671 1240.17 63.961 1224.06 63.961C1207.95 63.961 1200.32 58.671 1191.49 52.551C1182.33 46.201 1171.95 39.001 1152.07 39.001H1152.06C1132.19 39.001 1121.8 46.201 1112.64 52.551C1103.81 58.671 1096.18 63.961 1080.06 63.961C1063.94 63.961 1056.31 58.671 1047.48 52.551C1038.32 46.201 1027.94 39.001 1008.06 39.001H1008.04C988.16 39.001 977.78 46.201 968.62 52.551C959.79 58.671 952.16 63.961 936.05 63.961C919.94 63.961 912.31 58.671 903.48 52.551C894.32 46.201 883.94 39.001 864.06 39.001H864.04C844.17 39.001 833.78 46.201 824.62 52.551C815.79 58.671 808.16 63.961 792.04 63.961C775.92 63.961 768.29 58.671 759.46 52.551C750.3 46.201 739.92 39.001 720.04 39.001H720.02C700.14 39.001 689.76 46.201 680.6 52.551C671.77 58.671 664.14 63.961 648.03 63.961C631.92 63.961 624.29 58.671 615.46 52.551C606.3 46.201 595.92 39.001 576.04 39.001H576.02C556.15 39.001 545.76 46.201 536.6 52.551C527.77 58.671 520.14 63.961 504.02 63.961C487.9 63.961 480.27 58.671 471.44 52.551C462.28 46.201 451.89 39.001 432.01 39.001C412.13 39.001 401.75 46.201 392.59 52.551C383.76 58.671 376.13 63.961 359.99 63.961C343.85 63.961 336.25 58.671 327.42 52.551C318.26 46.201 307.89 39.001 288.02 39.001V51.001C304.13 51.001 311.75 56.291 320.58 62.411C329.74 68.761 340.12 75.961 359.99 75.961C379.86 75.961 390.26 68.761 399.42 62.411C408.25 56.291 415.88 51.001 432 51.001C448.12 51.001 455.76 56.291 464.6 62.411C473.76 68.761 484.14 75.961 504.02 75.961C523.9 75.961 534.28 68.761 543.44 62.411C552.27 56.291 559.9 51.001 576.03 51.001C592.14 51.001 599.76 56.291 608.58 62.411C617.74 68.761 628.12 75.961 647.99 75.961H648.05C667.92 75.961 678.3 68.761 687.46 62.411C696.28 56.291 703.91 51.001 720.01 51.001C736.14 51.001 743.77 56.291 752.6 62.411C761.76 68.761 772.14 75.961 792.02 75.961C811.9 75.961 822.28 68.761 831.44 62.411C840.27 56.291 847.9 51.001 864.03 51.001C880.14 51.001 887.76 56.291 896.58 62.411C905.74 68.761 916.12 75.961 935.99 75.961H936.05C955.92 75.961 966.3 68.761 975.46 62.411C984.28 56.291 991.91 51.001 1008.01 51.001C1024.14 51.001 1031.77 56.291 1040.6 62.411C1049.76 68.761 1060.14 75.961 1080.02 75.961C1099.9 75.961 1110.28 68.761 1119.44 62.411C1128.27 56.291 1135.9 51.001 1152.03 51.001C1168.14 51.001 1175.76 56.291 1184.58 62.411C1193.74 68.761 1204.12 75.961 1223.99 75.961H1224.05C1243.92 75.961 1254.3 68.761 1263.46 62.411C1272.28 56.291 1279.9 51.001 1296.01 51.001C1312.14 51.001 1319.77 56.291 1328.6 62.411C1337.76 68.761 1348.14 75.961 1368.02 75.961C1387.9 75.961 1398.28 68.761 1407.44 62.411C1416.27 56.291 1423.9 51.001 1440.03 51.001C1456.14 51.001 1463.76 56.291 1472.58 62.411C1481.74 68.761 1492.12 75.961 1511.99 75.961H1512.05C1531.92 75.961 1542.3 68.761 1551.46 62.411C1560.28 56.291 1567.91 51.001 1584.01 51.001C1600.14 51.001 1607.77 56.291 1616.6 62.411C1625.76 68.761 1636.14 75.961 1656.02 75.961C1675.9 75.961 1686.28 68.761 1695.44 62.411C1704.28 56.291 1711.91 51.001 1728.04 51.001V39.001C1708.15 39.001 1697.76 46.201 1688.6 52.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 89.551C239.79 95.671 232.16 100.961 216.04 100.961C199.92 100.961 192.29 95.671 183.46 89.551C174.3 83.201 163.92 76.001 144.04 76.001H144.02C124.14 76.001 113.76 83.201 104.6 89.551C95.7701 95.671 88.15 100.961 72.04 100.961C55.9301 100.961 48.2999 95.671 39.48 89.551C30.3199 83.201 19.9401 76.001 0.0600586 76.001H0.0400391C-19.84 76.001 -30.22 83.201 -39.38 89.551C-48.21 95.671 -55.84 100.961 -71.96 100.961C-88.08 100.961 -95.71 95.671 -104.54 89.551C-113.7 83.201 -124.08 76.001 -143.96 76.001H-143.98C-163.85 76.001 -174.23 83.201 -183.39 89.551C-192.22 95.671 -199.85 100.961 -215.96 100.961C-232.07 100.961 -239.7 95.671 -248.53 89.551C-257.69 83.201 -268.07 76.001 -287.95 76.001H-287.96C-307.83 76.001 -318.22 83.201 -327.38 89.551C-336.21 95.671 -343.84 100.961 -359.96 100.961C-376.08 100.961 -383.71 95.671 -392.54 89.551C-401.7 83.201 -412.08 76.001 -431.96 76.001H-431.98C-451.86 76.001 -462.24 83.201 -471.4 89.551C-480.23 95.671 -487.86 100.961 -503.97 100.961C-520.08 100.961 -527.71 95.671 -536.54 89.551C-545.7 83.201 -556.08 76.001 -575.96 76.001H-575.98C-595.85 76.001 -606.24 83.201 -615.4 89.551C-624.23 95.671 -631.86 100.961 -647.98 100.961C-664.1 100.961 -671.73 95.671 -680.56 89.551C-689.72 83.201 -700.1 76.001 -719.98 76.001H-720C-739.88 76.001 -750.26 83.201 -759.42 89.551C-768.25 95.671 -775.88 100.961 -791.99 100.961C-808.1 100.961 -815.73 95.671 -824.56 89.551C-833.72 83.201 -844.1 76.001 -863.98 76.001H-864C-883.87 76.001 -894.26 83.201 -903.42 89.551C-912.25 95.671 -919.88 100.961 -936 100.961C-952.12 100.961 -959.75 95.671 -968.58 89.551C-977.74 83.201 -988.13 76.001 -1008.01 76.001C-1027.89 76.001 -1038.27 83.201 -1047.43 89.551C-1056.26 95.671 -1063.89 100.961 -1080.03 100.961C-1096.17 100.961 -1103.77 95.671 -1112.6 89.551C-1121.76 83.201 -1132.13 76.001 -1152 76.001V88.001C-1135.89 88.001 -1128.27 93.291 -1119.44 99.411C-1110.28 105.761 -1099.9 112.961 -1080.03 112.961C-1060.16 112.961 -1049.76 105.761 -1040.6 99.411C-1031.77 93.291 -1024.14 88.001 -1008.02 88.001C-991.9 88.001 -984.26 93.291 -975.42 99.411C-966.26 105.761 -955.88 112.961 -936 112.961C-916.12 112.961 -905.74 105.761 -896.58 99.411C-887.75 93.291 -880.12 88.001 -863.99 88.001C-847.88 88.001 -840.26 93.291 -831.44 99.411C-822.28 105.761 -811.9 112.961 -792.03 112.961H-791.97C-772.1 112.961 -761.72 105.761 -752.56 99.411C-743.74 93.291 -736.11 88.001 -720.01 88.001C-703.88 88.001 -696.25 93.291 -687.42 99.411C-678.26 105.761 -667.88 112.961 -648 112.961C-628.12 112.961 -617.74 105.761 -608.58 99.411C-599.75 93.291 -592.12 88.001 -575.99 88.001C-559.88 88.001 -552.26 93.291 -543.44 99.411C-534.28 105.761 -523.9 112.961 -504.03 112.961H-503.97C-484.1 112.961 -473.72 105.761 -464.56 99.411C-455.74 93.291 -448.11 88.001 -432.01 88.001C-415.88 88.001 -408.25 93.291 -399.42 99.411C-390.26 105.761 -379.88 112.961 -360 112.961C-340.12 112.961 -329.74 105.761 -320.58 99.411C-311.75 93.291 -304.12 88.001 -287.99 88.001C-271.88 88.001 -264.26 93.291 -255.44 99.411C-246.28 105.761 -235.9 112.961 -216.03 112.961H-215.97C-196.1 112.961 -185.72 105.761 -176.56 99.411C-167.74 93.291 -160.12 88.001 -144.01 88.001C-127.88 88.001 -120.25 93.291 -111.42 99.411C-102.26 105.761 -91.88 112.961 -72 112.961C-52.12 112.961 -41.74 105.761 -32.58 99.411C-23.75 93.291 -16.12 88.001 0.0100098 88.001C16.12 88.001 23.7401 93.291 32.5601 99.411C41.7201 105.761 52.1001 112.961 71.9701 112.961H72.03C91.9 112.961 102.28 105.761 111.44 99.411C120.26 93.291 127.89 88.001 143.99 88.001C160.12 88.001 167.75 93.291 176.58 99.411C185.74 105.761 196.12 112.961 216 112.961C235.88 112.961 246.26 105.761 255.42 99.411C264.26 93.291 271.89 88.001 288.02 88.001V76.001C268.13 76.001 257.74 83.201 248.58 89.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 89.551C1679.81 95.671 1672.18 100.961 1656.06 100.961C1639.94 100.961 1632.31 95.671 1623.48 89.551C1614.32 83.201 1603.94 76.001 1584.06 76.001H1584.04C1564.16 76.001 1553.78 83.201 1544.62 89.551C1535.79 95.671 1528.17 100.961 1512.06 100.961C1495.95 100.961 1488.32 95.671 1479.5 89.551C1470.34 83.201 1459.96 76.001 1440.08 76.001H1440.06C1420.18 76.001 1409.8 83.201 1400.64 89.551C1391.81 95.671 1384.18 100.961 1368.06 100.961C1351.94 100.961 1344.31 95.671 1335.48 89.551C1326.32 83.201 1315.94 76.001 1296.06 76.001H1296.04C1276.17 76.001 1265.79 83.201 1256.63 89.551C1247.8 95.671 1240.17 100.961 1224.06 100.961C1207.95 100.961 1200.32 95.671 1191.49 89.551C1182.33 83.201 1171.95 76.001 1152.07 76.001H1152.06C1132.19 76.001 1121.8 83.201 1112.64 89.551C1103.81 95.671 1096.18 100.961 1080.06 100.961C1063.94 100.961 1056.31 95.671 1047.48 89.551C1038.32 83.201 1027.94 76.001 1008.06 76.001H1008.04C988.16 76.001 977.78 83.201 968.62 89.551C959.79 95.671 952.16 100.961 936.05 100.961C919.94 100.961 912.31 95.671 903.48 89.551C894.32 83.201 883.94 76.001 864.06 76.001H864.04C844.17 76.001 833.78 83.201 824.62 89.551C815.79 95.671 808.16 100.961 792.04 100.961C775.92 100.961 768.29 95.671 759.46 89.551C750.3 83.201 739.92 76.001 720.04 76.001H720.02C700.14 76.001 689.76 83.201 680.6 89.551C671.77 95.671 664.14 100.961 648.03 100.961C631.92 100.961 624.29 95.671 615.46 89.551C606.3 83.201 595.92 76.001 576.04 76.001H576.02C556.15 76.001 545.76 83.201 536.6 89.551C527.77 95.671 520.14 100.961 504.02 100.961C487.9 100.961 480.27 95.671 471.44 89.551C462.28 83.201 451.89 76.001 432.01 76.001C412.13 76.001 401.75 83.201 392.59 89.551C383.76 95.671 376.13 100.961 359.99 100.961C343.85 100.961 336.25 95.671 327.42 89.551C318.26 83.201 307.89 76.001 288.02 76.001V88.001C304.13 88.001 311.75 93.291 320.58 99.411C329.74 105.761 340.12 112.961 359.99 112.961C379.86 112.961 390.26 105.761 399.42 99.411C408.25 93.291 415.88 88.001 432 88.001C448.12 88.001 455.76 93.291 464.6 99.411C473.76 105.761 484.14 112.961 504.02 112.961C523.9 112.961 534.28 105.761 543.44 99.411C552.27 93.291 559.9 88.001 576.03 88.001C592.14 88.001 599.76 93.291 608.58 99.411C617.74 105.761 628.12 112.961 647.99 112.961H648.05C667.92 112.961 678.3 105.761 687.46 99.411C696.28 93.291 703.91 88.001 720.01 88.001C736.14 88.001 743.77 93.291 752.6 99.411C761.76 105.761 772.14 112.961 792.02 112.961C811.9 112.961 822.28 105.761 831.44 99.411C840.27 93.291 847.9 88.001 864.03 88.001C880.14 88.001 887.76 93.291 896.58 99.411C905.74 105.761 916.12 112.961 935.99 112.961H936.05C955.92 112.961 966.3 105.761 975.46 99.411C984.28 93.291 991.91 88.001 1008.01 88.001C1024.14 88.001 1031.77 93.291 1040.6 99.411C1049.76 105.761 1060.14 112.961 1080.02 112.961C1099.9 112.961 1110.28 105.761 1119.44 99.411C1128.27 93.291 1135.9 88.001 1152.03 88.001C1168.14 88.001 1175.76 93.291 1184.58 99.411C1193.74 105.761 1204.12 112.961 1223.99 112.961H1224.05C1243.92 112.961 1254.3 105.761 1263.46 99.411C1272.28 93.291 1279.9 88.001 1296.01 88.001C1312.14 88.001 1319.77 93.291 1328.6 99.411C1337.76 105.761 1348.14 112.961 1368.02 112.961C1387.9 112.961 1398.28 105.761 1407.44 99.411C1416.27 93.291 1423.9 88.001 1440.03 88.001C1456.14 88.001 1463.76 93.291 1472.58 99.411C1481.74 105.761 1492.12 112.961 1511.99 112.961H1512.05C1531.92 112.961 1542.3 105.761 1551.46 99.411C1560.28 93.291 1567.91 88.001 1584.01 88.001C1600.14 88.001 1607.77 93.291 1616.6 99.411C1625.76 105.761 1636.14 112.961 1656.02 112.961C1675.9 112.961 1686.28 105.761 1695.44 99.411C1704.28 93.291 1711.91 88.001 1728.04 88.001V76.001C1708.15 76.001 1697.76 83.201 1688.6 89.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M248.62 126.551C239.79 132.671 232.16 137.961 216.04 137.961C199.92 137.961 192.29 132.671 183.46 126.551C174.3 120.201 163.92 113.001 144.04 113.001H144.02C124.14 113.001 113.76 120.201 104.6 126.551C95.7701 132.671 88.15 137.961 72.04 137.961C55.9301 137.961 48.2999 132.671 39.48 126.551C30.3199 120.201 19.9401 113.001 0.0600586 113.001H0.0400391C-19.84 113.001 -30.22 120.201 -39.38 126.551C-48.21 132.671 -55.84 137.961 -71.96 137.961C-88.08 137.961 -95.71 132.671 -104.54 126.551C-113.7 120.201 -124.08 113.001 -143.96 113.001H-143.98C-163.85 113.001 -174.23 120.201 -183.39 126.551C-192.22 132.671 -199.85 137.961 -215.96 137.961C-232.07 137.961 -239.7 132.671 -248.53 126.551C-257.69 120.201 -268.07 113.001 -287.95 113.001H-287.96C-307.83 113.001 -318.22 120.201 -327.38 126.551C-336.21 132.671 -343.84 137.961 -359.96 137.961C-376.08 137.961 -383.71 132.671 -392.54 126.551C-401.7 120.201 -412.08 113.001 -431.96 113.001H-431.98C-451.86 113.001 -462.24 120.201 -471.4 126.551C-480.23 132.671 -487.86 137.961 -503.97 137.961C-520.08 137.961 -527.71 132.671 -536.54 126.551C-545.7 120.201 -556.08 113.001 -575.96 113.001H-575.98C-595.85 113.001 -606.24 120.201 -615.4 126.551C-624.23 132.671 -631.86 137.961 -647.98 137.961C-664.1 137.961 -671.73 132.671 -680.56 126.551C-689.72 120.201 -700.1 113.001 -719.98 113.001H-720C-739.88 113.001 -750.26 120.201 -759.42 126.551C-768.25 132.671 -775.88 137.961 -791.99 137.961C-808.1 137.961 -815.73 132.671 -824.56 126.551C-833.72 120.201 -844.1 113.001 -863.98 113.001H-864C-883.87 113.001 -894.26 120.201 -903.42 126.551C-912.25 132.671 -919.88 137.961 -936 137.961C-952.12 137.961 -959.75 132.671 -968.58 126.551C-977.74 120.201 -988.13 113.001 -1008.01 113.001C-1027.89 113.001 -1038.27 120.201 -1047.43 126.551C-1056.26 132.671 -1063.89 137.961 -1080.03 137.961C-1096.17 137.961 -1103.77 132.671 -1112.6 126.551C-1121.76 120.201 -1132.13 113.001 -1152 113.001V125.001C-1135.89 125.001 -1128.27 130.291 -1119.44 136.411C-1110.28 142.761 -1099.9 149.961 -1080.03 149.961C-1060.16 149.961 -1049.76 142.761 -1040.6 136.411C-1031.77 130.291 -1024.14 125.001 -1008.02 125.001C-991.9 125.001 -984.26 130.291 -975.42 136.411C-966.26 142.761 -955.88 149.961 -936 149.961C-916.12 149.961 -905.74 142.761 -896.58 136.411C-887.75 130.291 -880.12 125.001 -863.99 125.001C-847.88 125.001 -840.26 130.291 -831.44 136.411C-822.28 142.761 -811.9 149.961 -792.03 149.961H-791.97C-772.1 149.961 -761.72 142.761 -752.56 136.411C-743.74 130.291 -736.11 125.001 -720.01 125.001C-703.88 125.001 -696.25 130.291 -687.42 136.411C-678.26 142.761 -667.88 149.961 -648 149.961C-628.12 149.961 -617.74 142.761 -608.58 136.411C-599.75 130.291 -592.12 125.001 -575.99 125.001C-559.88 125.001 -552.26 130.291 -543.44 136.411C-534.28 142.761 -523.9 149.961 -504.03 149.961H-503.97C-484.1 149.961 -473.72 142.761 -464.56 136.411C-455.74 130.291 -448.11 125.001 -432.01 125.001C-415.88 125.001 -408.25 130.291 -399.42 136.411C-390.26 142.761 -379.88 149.961 -360 149.961C-340.12 149.961 -329.74 142.761 -320.58 136.411C-311.75 130.291 -304.12 125.001 -287.99 125.001C-271.88 125.001 -264.26 130.291 -255.44 136.411C-246.28 142.761 -235.9 149.961 -216.03 149.961H-215.97C-196.1 149.961 -185.72 142.761 -176.56 136.411C-167.74 130.291 -160.12 125.001 -144.01 125.001C-127.88 125.001 -120.25 130.291 -111.42 136.411C-102.26 142.761 -91.88 149.961 -72 149.961C-52.12 149.961 -41.74 142.761 -32.58 136.411C-23.75 130.291 -16.12 125.001 0.0100098 125.001C16.12 125.001 23.7401 130.291 32.5601 136.411C41.7201 142.761 52.1001 149.961 71.9701 149.961H72.03C91.9 149.961 102.28 142.761 111.44 136.411C120.26 130.291 127.89 125.001 143.99 125.001C160.12 125.001 167.75 130.291 176.58 136.411C185.74 142.761 196.12 149.961 216 149.961C235.88 149.961 246.26 142.761 255.42 136.411C264.26 130.291 271.89 125.001 288.02 125.001V113.001C268.13 113.001 257.74 120.201 248.58 126.551H248.62Z\"\n                    fill=\"#F6CFE4\" \/>\n                <path\n                    d=\"M1688.64 126.551C1679.81 132.671 1672.18 137.961 1656.06 137.961C1639.94 137.961 1632.31 132.671 1623.48 126.551C1614.32 120.201 1603.94 113.001 1584.06 113.001H1584.04C1564.16 113.001 1553.78 120.201 1544.62 126.551C1535.79 132.671 1528.17 137.961 1512.06 137.961C1495.95 137.961 1488.32 132.671 1479.5 126.551C1470.34 120.201 1459.96 113.001 1440.08 113.001H1440.06C1420.18 113.001 1409.8 120.201 1400.64 126.551C1391.81 132.671 1384.18 137.961 1368.06 137.961C1351.94 137.961 1344.31 132.671 1335.48 126.551C1326.32 120.201 1315.94 113.001 1296.06 113.001H1296.04C1276.17 113.001 1265.79 120.201 1256.63 126.551C1247.8 132.671 1240.17 137.961 1224.06 137.961C1207.95 137.961 1200.32 132.671 1191.49 126.551C1182.33 120.201 1171.95 113.001 1152.07 113.001H1152.06C1132.19 113.001 1121.8 120.201 1112.64 126.551C1103.81 132.671 1096.18 137.961 1080.06 137.961C1063.94 137.961 1056.31 132.671 1047.48 126.551C1038.32 120.201 1027.94 113.001 1008.06 113.001H1008.04C988.16 113.001 977.78 120.201 968.62 126.551C959.79 132.671 952.16 137.961 936.05 137.961C919.94 137.961 912.31 132.671 903.48 126.551C894.32 120.201 883.94 113.001 864.06 113.001H864.04C844.17 113.001 833.78 120.201 824.62 126.551C815.79 132.671 808.16 137.961 792.04 137.961C775.92 137.961 768.29 132.671 759.46 126.551C750.3 120.201 739.92 113.001 720.04 113.001H720.02C700.14 113.001 689.76 120.201 680.6 126.551C671.77 132.671 664.14 137.961 648.03 137.961C631.92 137.961 624.29 132.671 615.46 126.551C606.3 120.201 595.92 113.001 576.04 113.001H576.02C556.15 113.001 545.76 120.201 536.6 126.551C527.77 132.671 520.14 137.961 504.02 137.961C487.9 137.961 480.27 132.671 471.44 126.551C462.28 120.201 451.89 113.001 432.01 113.001C412.13 113.001 401.75 120.201 392.59 126.551C383.76 132.671 376.13 137.961 359.99 137.961C343.85 137.961 336.25 132.671 327.42 126.551C318.26 120.201 307.89 113.001 288.02 113.001V125.001C304.13 125.001 311.75 130.291 320.58 136.411C329.74 142.761 340.12 149.961 359.99 149.961C379.86 149.961 390.26 142.761 399.42 136.411C408.25 130.291 415.88 125.001 432 125.001C448.12 125.001 455.76 130.291 464.6 136.411C473.76 142.761 484.14 149.961 504.02 149.961C523.9 149.961 534.28 142.761 543.44 136.411C552.27 130.291 559.9 125.001 576.03 125.001C592.14 125.001 599.76 130.291 608.58 136.411C617.74 142.761 628.12 149.961 647.99 149.961H648.05C667.92 149.961 678.3 142.761 687.46 136.411C696.28 130.291 703.91 125.001 720.01 125.001C736.14 125.001 743.77 130.291 752.6 136.411C761.76 142.761 772.14 149.961 792.02 149.961C811.9 149.961 822.28 142.761 831.44 136.411C840.27 130.291 847.9 125.001 864.03 125.001C880.14 125.001 887.76 130.291 896.58 136.411C905.74 142.761 916.12 149.961 935.99 149.961H936.05C955.92 149.961 966.3 142.761 975.46 136.411C984.28 130.291 991.91 125.001 1008.01 125.001C1024.14 125.001 1031.77 130.291 1040.6 136.411C1049.76 142.761 1060.14 149.961 1080.02 149.961C1099.9 149.961 1110.28 142.761 1119.44 136.411C1128.27 130.291 1135.9 125.001 1152.03 125.001C1168.14 125.001 1175.76 130.291 1184.58 136.411C1193.74 142.761 1204.12 149.961 1223.99 149.961H1224.05C1243.92 149.961 1254.3 142.761 1263.46 136.411C1272.28 130.291 1279.9 125.001 1296.01 125.001C1312.14 125.001 1319.77 130.291 1328.6 136.411C1337.76 142.761 1348.14 149.961 1368.02 149.961C1387.9 149.961 1398.28 142.761 1407.44 136.411C1416.27 130.291 1423.9 125.001 1440.03 125.001C1456.14 125.001 1463.76 130.291 1472.58 136.411C1481.74 142.761 1492.12 149.961 1511.99 149.961H1512.05C1531.92 149.961 1542.3 142.761 1551.46 136.411C1560.28 130.291 1567.91 125.001 1584.01 125.001C1600.14 125.001 1607.77 130.291 1616.6 136.411C1625.76 142.761 1636.14 149.961 1656.02 149.961C1675.9 149.961 1686.28 142.761 1695.44 136.411C1704.28 130.291 1711.91 125.001 1728.04 125.001V113.001C1708.15 113.001 1697.76 120.201 1688.6 126.551H1688.64Z\"\n                    fill=\"#F6CFE4\" \/>\n            <\/g>\n            <defs>\n                <clipPath id=\"clip0_1140_15955\">\n                    <rect width=\"576\" height=\"151\" fill=\"white\" transform=\"translate(0 0.000976562)\" \/>\n                <\/clipPath>\n            <\/defs>\n        <\/svg>\n                <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"section_heading\">\n                    <h1>Plus d&#8217;informations<\/h1>\n                <\/div>\n            <\/div>\n        <\/div>\n                \n        <div class=\"row\">\n            <div class=\"col-sm-12\">\n                <div class=\"text_block\">\n                    <div class=\"txt_block_inner\">\n                        <h2><\/h2>\n                                                <ul class=\"icon_list\">\n                                                            <li>\n                                                                        <span><p><a href=\"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/vehicule-100-electrique\/\">Subvention v\u00e9hicule \u00e9lectrique<\/a><\/p>\n<p><a href=\"https:\/\/www.yverdon-energies.ch\/rouler-electrique-proprietaire\/\">Rouler \u00e9lectrique<\/a><\/p>\n<\/span>\n                                <\/li>\n                                                        <\/ul>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        \n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Installez des bornes de recharges de mani\u00e8re coordonn\u00e9e dans les immeubles collectifs et profitez de la subvention \u00e9quiwatt.<\/p>\n","protected":false},"author":2,"featured_media":13053,"template":"","programe-type":[325,326],"programe-category":[6],"profile":[31,36,40],"class_list":["post-13041","programes","type-programes","status-publish","has-post-thumbnail","hentry","programe-type-electricite","programe-type-mobilite","programe-category-subventions","profile-economies-subventions-entreprise","profile-economies-subventions-regie","profile-economies-subventions-proprietaire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies\" \/>\n<meta property=\"og:description\" content=\"Installez des bornes de recharges de mani\u00e8re coordonn\u00e9e dans les immeubles collectifs et profitez de la subvention \u00e9quiwatt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/\" \/>\n<meta property=\"og:site_name\" content=\"Yverdon \u00c9nergies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/@YverdonEnergies\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T16:10:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto-home_bornes-recharge.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"397\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/\",\"url\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/\",\"name\":\"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/picto-home_bornes-recharge.webp\",\"datePublished\":\"2025-01-08T14:06:59+00:00\",\"dateModified\":\"2026-01-13T16:10:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/picto-home_bornes-recharge.webp\",\"contentUrl\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/picto-home_bornes-recharge.webp\",\"width\":397,\"height\":397,\"caption\":\"Subvention borne de recharge - Yverdon \u00c9nergies\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/infrastructure-de-recharge-a-usage-prive-intelligent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programmes\",\"item\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/programmes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/\",\"name\":\"Yverdon \u00c9nergies\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#organization\",\"name\":\"Yverdon \u00c9nergies\",\"url\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_new.svg\",\"contentUrl\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo_new.svg\",\"width\":127,\"height\":56,\"caption\":\"Yverdon \u00c9nergies\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yverdon-energies.ch\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/@YverdonEnergies\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/","og_locale":"pt_PT","og_type":"article","og_title":"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies","og_description":"Installez des bornes de recharges de mani\u00e8re coordonn\u00e9e dans les immeubles collectifs et profitez de la subvention \u00e9quiwatt.","og_url":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/","og_site_name":"Yverdon \u00c9nergies","article_publisher":"https:\/\/www.facebook.com\/@YverdonEnergies\/","article_modified_time":"2026-01-13T16:10:02+00:00","og_image":[{"width":397,"height":397,"url":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto-home_bornes-recharge.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/","url":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/","name":"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent &#8211; Yverdon \u00c9nergies","isPartOf":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/#primaryimage"},"image":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto-home_bornes-recharge.webp","datePublished":"2025-01-08T14:06:59+00:00","dateModified":"2026-01-13T16:10:02+00:00","breadcrumb":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/"]}]},{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/#primaryimage","url":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto-home_bornes-recharge.webp","contentUrl":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2025\/01\/picto-home_bornes-recharge.webp","width":397,"height":397,"caption":"Subvention borne de recharge - Yverdon \u00c9nergies"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/infrastructure-de-recharge-a-usage-prive-intelligent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.yverdon-energies.ch\/pt\/"},{"@type":"ListItem","position":2,"name":"Programmes","item":"https:\/\/www.yverdon-energies.ch\/pt\/programmes\/"},{"@type":"ListItem","position":3,"name":"Infrastructure de recharge \u00e0 usage priv\u00e9 intelligent"}]},{"@type":"WebSite","@id":"https:\/\/www.yverdon-energies.ch\/pt\/#website","url":"https:\/\/www.yverdon-energies.ch\/pt\/","name":"Yverdon \u00c9nergies","description":"","publisher":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yverdon-energies.ch\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/www.yverdon-energies.ch\/pt\/#organization","name":"Yverdon \u00c9nergies","url":"https:\/\/www.yverdon-energies.ch\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/www.yverdon-energies.ch\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2023\/07\/logo_new.svg","contentUrl":"https:\/\/www.yverdon-energies.ch\/wp-content\/uploads\/2023\/07\/logo_new.svg","width":127,"height":56,"caption":"Yverdon \u00c9nergies"},"image":{"@id":"https:\/\/www.yverdon-energies.ch\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/@YverdonEnergies\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programes\/13041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programes"}],"about":[{"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/types\/programes"}],"author":[{"embeddable":true,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":10,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programes\/13041\/revisions"}],"predecessor-version":[{"id":15101,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programes\/13041\/revisions\/15101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/media\/13053"}],"wp:attachment":[{"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/media?parent=13041"}],"wp:term":[{"taxonomy":"programe-type","embeddable":true,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programe-type?post=13041"},{"taxonomy":"programe-category","embeddable":true,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/programe-category?post=13041"},{"taxonomy":"profile","embeddable":true,"href":"https:\/\/www.yverdon-energies.ch\/pt\/wp-json\/wp\/v2\/profile?post=13041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}